{"id":3645,"date":"2024-08-29T17:00:01","date_gmt":"2024-08-29T21:00:01","guid":{"rendered":"https:\/\/econostrum.info\/canada\/?p=3645"},"modified":"2024-08-29T10:49:12","modified_gmt":"2024-08-29T14:49:12","slug":"quebec-fonctionnaires-prime-800-par-an","status":"publish","type":"post","link":"https:\/\/econostrum.info\/canada\/quebec-fonctionnaires-prime-800-par-an\/","title":{"rendered":"Au Qu\u00e9bec, ces fonctionnaires vont toucher une prime de 800 $ par an"},"content":{"rendered":"<p><strong>Bonne nouvelle pour les fonctionnaires au Qu\u00e9bec, en particulier ceux qui sont les plus fid\u00e8les \u00e0 leur poste. \u00c0 partir du 1\u1d49\u02b3 avril 2025, le gouvernement qu\u00e9b\u00e9cois accordera une prime annuelle pouvant aller jusqu&rsquo;\u00e0 800 $ aux employ\u00e9s de l&rsquo;\u00c9tat qui travaillent dans le m\u00eame minist\u00e8re ou organisme depuis plusieurs ann\u00e9es.<\/strong><\/p>\n<p>Le gouvernement du Qu\u00e9bec a choisi de r\u00e9compenser ses fonctionnaires les plus loyaux. En effet, dans le cadre de l\u2019entente sur les conditions de travail approuv\u00e9e le mardi 27 ao\u00fbt 2024 par les 27 000 membres du Syndicat de la fonction publique et parapublique du Qu\u00e9bec (SFPQ), une <strong>prime de \u00ab fid\u00e9lit\u00e9 en emploi \u00bb<\/strong> a \u00e9t\u00e9 instaur\u00e9e pour les travailleurs qui restent fid\u00e8les \u00e0 leur poste sans changer fr\u00e9quemment d&#8217;emploi.<\/p>\n<p>Selon le pr\u00e9sident du Syndicat de la fonction publique et parapublique du Qu\u00e9bec (SFPQ), cette prime annuelle sera vers\u00e9e aux \u00ab\u00a0fonctionnaires fid\u00e8les\u00a0\u00bb tous le 1er avril \u00e0 partir de 2025. \u00ab\u00a0C\u2019est une prime de remerciement que le gouvernement verse tous les 1er avril pour dire aux gens : merci beaucoup d\u2019\u00eatre rest\u00e9 chez nous. Parce qu\u2019on sait qu\u2019au bout de cinq ans dans un m\u00eame poste, une personne est beaucoup plus productive qu\u2019apr\u00e8s six mois \u00bb, explique Christian Daigle au Journal du Qu\u00e9bec.<\/p>\n<h2>Voici le montant de la prime de fid\u00e9lit\u00e9 pour les fonctionnaires<\/h2>\n<p>Ainsi donc, \u00e0 partir du 1\u1d49\u02b3 avril 2025, les employ\u00e9s ayant accumul\u00e9 trois ann\u00e9es cons\u00e9cutives d\u2019anciennet\u00e9 dans le m\u00eame minist\u00e8re ou organisme et qui auront fourni un \u00ab rendement satisfaisant \u00bb toucheront un <strong>montant forfaitaire de 300\u2009$<\/strong>. La prime atteint plus du double lorsque le fonctionnaire a travaill\u00e9 au m\u00eame endroit pendant cinq ans ou plus. Les employ\u00e9s \u00ab fid\u00e8les \u00bb les plus exp\u00e9riment\u00e9s encaisseront ainsi <strong>800\u2009$ le 1er avril de chaque ann\u00e9e<\/strong>.<\/p>\n<p>Avec cette mesure, l\u2019employeur vise \u00e0 <strong>am\u00e9liorer la r\u00e9tention du personnel<\/strong> et \u00e0 limiter la rotation constante des fonctionnaires entre les diff\u00e9rents minist\u00e8res et organismes. C&rsquo;est \u00e9galement une victoire pour les travailleurs. \u00ab Les gens chez nous voulaient des incitatifs et disaient : \u00e7a fait 15 ans, 20 ans que je suis l\u00e0, j\u2019ai peut-\u00eatre droit \u00e0 un petit merci \u00bb, souligne Christian Daigle. \u00ab C\u2019est important pour la r\u00e9tention de personnel, pour ne pas que les gens aillent \u00e0 l\u2019externe, surtout lorsque les conditions salariales dans le secteur priv\u00e9 sont attrayantes\u00a0\u00bb, ajoute-t-il<\/p>\n<p>Par ailleurs, les quelque 35 000 fonctionnaires du gouvernement b\u00e9n\u00e9ficient \u00e9galement d\u2019un avantage similaire. Cependant, pour les fonctionnaires affili\u00e9s au Syndicat des professionnels du gouvernement du Qu\u00e9bec (SPGQ), la \u00ab mesure de fid\u00e9lit\u00e9 \u00bb prend une forme diff\u00e9rente. Apr\u00e8s trois ans d\u2019anciennet\u00e9 dans le m\u00eame minist\u00e8re, ces employ\u00e9s de l\u2019\u00c9tat auront droit \u00e0<strong> une journ\u00e9e de cong\u00e9 mobile suppl\u00e9mentaire<\/strong>. \u00c0 partir du 1er avril, les fonctionnaires comptant au moins cinq ann\u00e9es cons\u00e9cutives dans le m\u00eame poste accumuleront trois jours de cong\u00e9 suppl\u00e9mentaires dans leur banque de cong\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonne nouvelle pour les fonctionnaires au Qu\u00e9bec, en particulier ceux qui sont les plus fid\u00e8les \u00e0 leur poste. \u00c0 partir du 1\u1d49\u02b3 avril 2025, le gouvernement qu\u00e9b\u00e9cois accordera une prime &#8230; <a title=\"Au Qu\u00e9bec, ces fonctionnaires vont toucher une prime de 800 $ par an\" class=\"read-more\" href=\"https:\/\/econostrum.info\/canada\/quebec-fonctionnaires-prime-800-par-an\/\" aria-label=\"Read more about Au Qu\u00e9bec, ces fonctionnaires vont toucher une prime de 800 $ par an\"> <\/a><\/p>\n","protected":false},"author":27,"featured_media":3655,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3645","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/posts\/3645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/comments?post=3645"}],"version-history":[{"count":0,"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/posts\/3645\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/media\/3655"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/media?parent=3645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/categories?post=3645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/tags?post=3645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}