{"id":3467,"date":"2024-08-25T17:00:53","date_gmt":"2024-08-25T21:00:53","guid":{"rendered":"https:\/\/econostrum.info\/canada\/?p=3467"},"modified":"2024-08-25T06:41:12","modified_gmt":"2024-08-25T10:41:12","slug":"ottawa-etudiants-etrangers-francophones","status":"publish","type":"post","link":"https:\/\/econostrum.info\/canada\/ottawa-etudiants-etrangers-francophones\/","title":{"rendered":"Ottawa : Plus de 2000 \u00e9tudiants \u00e9trangers francophones dispens\u00e9s du plafond des permis d\u2019\u00e9tudes"},"content":{"rendered":"<p><strong>Ottawa met au point un nouveau programme pour les \u00e9tudiants \u00e9trangers francophones, facilitant leur acc\u00e8s aux \u00e9tudes postsecondaires.<\/strong><\/p>\n<p>Marc Miller, le ministre de l\u2019Immigration, a r\u00e9cemment annonc\u00e9 une grande nouvelle pour les \u00e9tudiants francophones. Ceux qui souhaitent obtenir un <strong>permis d\u2019\u00e9tudes \u00e0 l\u2019ext\u00e9rieur d\u2019Ottawa<\/strong> seront dor\u00e9navant exempt\u00e9s du plafond impos\u00e9 par le gouvernement f\u00e9d\u00e9ral en janvier 2024.<\/p>\n<h2><strong>Plus de 2000 \u00e9tudiants \u00e9trangers exempt\u00e9s <\/strong><\/h2>\n<p>Le ministre Miller a pr\u00e9cis\u00e9 dans un<a href=\"https:\/\/www.canada.ca\/fr\/immigration-refugies-citoyennete\/nouvelles\/2024\/08\/favoriser-la-vitalite-des-communautes-francophones-par-laccueil-detudiants-etrangers-et-dimmigrants-dexpression-francaise.html\" target=\"_blank\" rel=\"noopener\"> communiqu\u00e9<\/a> qu\u2019une exemption de ce plafond sera accord\u00e9e aux \u00e9tudiants \u00e9trangers francophones. Cette mesure sera int\u00e9gr\u00e9e dans un nouveau programme qui permettra \u00e0 2 300 \u00e9tudiants francophones \u00ab d\u2019obtenir des permis d\u2019\u00e9tudes en dehors du plafond fix\u00e9 par le gouvernement pour les <a href=\"https:\/\/econostrum.info\/canada\/ottawa-residence-permanente-etrangers\/\" target=\"_blank\" rel=\"noopener\">\u00e9tudiants \u00e9trangers<\/a> en 2024, avec une r\u00e9\u00e9valuation des chiffres pr\u00e9vue en 2025 si le programme est jug\u00e9 concluant \u00bb.<\/p>\n<p>D\u2019apr\u00e8s l\u2019Association des coll\u00e8ges et des universit\u00e9s de la francophonie canadienne (ACUFC), lors de la rentr\u00e9e de septembre 2023, environ <strong>11 500 permis d\u2019\u00e9tudes ont \u00e9t\u00e9 d\u00e9livr\u00e9s<\/strong>. Les permis \u00e9mis dans le cadre du programme pour les <strong>\u00e9tudiants \u00e9trangers francophones ne repr\u00e9sentaient que 20 %<\/strong> de ce total.<\/p>\n<h2>Un programme qui satisfait tout le monde<\/h2>\n<p>Ce nouveau programme, intitul\u00e9 Programme pilote pour les \u00e9tudiants dans les communaut\u00e9s francophones en situation minoritaire (PPECFSM), sera ouvert \u00e0 plusieurs pays. Il inclut diverses exemptions qui faciliteront l\u2019acc\u00e8s des \u00e9tudiants francophones aux \u00e9tudes postsecondaires au Canada.<\/p>\n<p>L\u2019un des principaux changements est la suppression de l\u2019obligation pour les \u00e9tudiants de prouver leur intention de quitter le territoire apr\u00e8s la fin de leurs \u00e9tudes. Ce changement repr\u00e9sente une avanc\u00e9e majeure, particuli\u00e8rement pour les \u00e9tudiants venant du Moyen-Orient et d\u2019Afrique, qui voyaient souvent cet aspect comme un obstacle.<\/p>\n<p>Le deuxi\u00e8me changement, tout aussi important, est la <strong>r\u00e9duction du seuil financier requis<\/strong>, d\u00e9sormais fix\u00e9 \u00e0 17 999 $, soit 3 000 $ de moins que pour les \u00e9tudiants \u00e9trangers venant de pays non francophones.<\/p>\n<p>Selon le ministre Miller, pour encourager <strong>l\u2019immigration en dehors du Qu\u00e9bec<\/strong>, les \u00e9tudiants participant \u00e0 ce programme auront un <strong>acc\u00e8s direct \u00e0 la r\u00e9sidence permanente<\/strong>, tout comme leur conjoint \u00ab les \u00e9poux ou conjoints de fait et les enfants \u00e0 charge des demandeurs principaux peuvent \u00e9galement venir au Canada dans le cadre du programme pilote et \u00e9ventuellement demander la r\u00e9sidence permanente \u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ottawa met au point un nouveau programme pour les \u00e9tudiants \u00e9trangers francophones, facilitant leur acc\u00e8s aux \u00e9tudes postsecondaires. Marc Miller, le ministre de l\u2019Immigration, a r\u00e9cemment annonc\u00e9 une grande nouvelle &#8230; <a title=\"Ottawa : Plus de 2000 \u00e9tudiants \u00e9trangers francophones dispens\u00e9s du plafond des permis d\u2019\u00e9tudes\" class=\"read-more\" href=\"https:\/\/econostrum.info\/canada\/ottawa-etudiants-etrangers-francophones\/\" aria-label=\"Read more about Ottawa : Plus de 2000 \u00e9tudiants \u00e9trangers francophones dispens\u00e9s du plafond des permis d\u2019\u00e9tudes\"> <\/a><\/p>\n","protected":false},"author":42,"featured_media":3500,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3467","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/posts\/3467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/comments?post=3467"}],"version-history":[{"count":0,"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/posts\/3467\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/media\/3500"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/media?parent=3467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/categories?post=3467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/tags?post=3467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}