{"id":3452,"date":"2024-08-24T09:00:12","date_gmt":"2024-08-24T13:00:12","guid":{"rendered":"https:\/\/econostrum.info\/canada\/?p=3452"},"modified":"2024-08-23T11:58:07","modified_gmt":"2024-08-23T15:58:07","slug":"livres-electroniques-delai-dedommager","status":"publish","type":"post","link":"https:\/\/econostrum.info\/canada\/livres-electroniques-delai-dedommager\/","title":{"rendered":"Livres \u00e9lectroniques : dernier d\u00e9lai pour se faire d\u00e9dommager"},"content":{"rendered":"<p><strong>Une action collective de livres \u00e9lectroniques qui a vis\u00e9 les revendeurs Google, Amazon, Sony, Kobo et iTunes s\u2019est conclue par un r\u00e8glement \u00e0 l\u2019amiable et donnera suite \u00e0 un d\u00e9dommagement pour certains clients. Toutefois, la date buttoir approche \u00e0 grands pas.<\/strong><\/p>\n<p>Une action collective contre les g\u00e9ants <strong>Google, Amazon, Sony, Kobo et iTunes<\/strong> a men\u00e9 \u00e0 une entente \u00e0 l&rsquo;amiable, offrant un <strong>d\u00e9dommagement \u00e0 certains clients au Canada<\/strong>. Ce r\u00e8glement national inclut des accords avec Hachette, Harper Collins, Macmillan, Penguin, Simon &amp; Schuster, ainsi qu\u2019Apple Inc. et Apple Canada Inc., visant \u00e0 indemniser les acheteurs de livres \u00e9lectroniques via ces plateformes entre 2010 et 2017. Mais qui peut profiter de cette indemnisation, et comment faire pour la r\u00e9clamer ?<\/p>\n<h2>\u00cates-vous admissible \u00e0 cette indemnisation ?<\/h2>\n<p>Selon le <a href=\"https:\/\/www.reglementcanadienlivrels.ca\/fr\/accueil\" target=\"_blank\" rel=\"noopener\">R\u00e8glement Canadien sur les livres \u00e9lectroniques<\/a>, pour \u00eatre \u00e9ligible \u00e0 une indemnisation, vous devez avoir \u00ab avoir achet\u00e9 des livres \u00e9lectroniques admissibles au Canada par un compte canadien aupr\u00e8s des d\u00e9taillants \u00e9lectroniques Google, Amazon, Sony, Kobo ou iTunes <strong>entre le 1\u1d49\u02b3 avril 2010 et le 10 mars 2017<\/strong> \u00bb. De plus, il est n\u00e9cessaire d&rsquo;avoir achet\u00e9 au moins <strong>12 livres \u00e9lectroniques<\/strong> pour que\u00a0\u00ab l&rsquo;Administrateur des R\u00e9clamations soit tenu d&rsquo;\u00e9mettre des paiements par ch\u00e8que ou par transfert \u00e9lectronique de fonds. \u00bb<\/p>\n<p>Le montant de l\u2019indemnisation sera calcul\u00e9 en fonction du<strong> nombre de livres admissibles<\/strong> que vous avez achet\u00e9s ainsi que de la valeur totale de vos achats.<\/p>\n<h2><strong>Processus de r\u00e9clamation <\/strong><\/h2>\n<p>Pour recevoir votre d\u00e9dommagement, il est imp\u00e9ratif de <strong>soumettre une r\u00e9clamation au plus tard le 23 septembre 2024<\/strong>. \u00ab Les Membres du R\u00e8glement qui ont achet\u00e9 12 livres \u00e9lectroniques admissibles ou plus en utilisant un compte Google, Amazon ou Sony, ou dont le compte iTunes ou Kobo n&rsquo;est plus actif ou n\u2019est plus associ\u00e9 \u00e0 une adresse courriel valide, devront soumettre un formulaire de r\u00e9clamation <strong>au plus tard le\u00a023 septembre 2024<\/strong>. Vous pouvez soumettre une r\u00e9clamation en ligne\u00a0<a href=\"https:\/\/www.reglementcanadienlivrels.ca\/fr\/reclamation\" target=\"_blank\" rel=\"noopener\">ici<\/a>. C&rsquo;est rapide, facile et s\u00e9curitaire.\u00a0\u00bb<\/p>\n<p>Si vous avez d\u00e9j\u00e0 re\u00e7u un courriel avec des informations sur votre compte iTunes ou Kobo, vous n\u2019\u00eates pas oblig\u00e9 de soumettre une r\u00e9clamation. \u00ab Votre part du Produit Net du R\u00e8glement pour l\u2019achat de livres \u00e9lectroniques admissibles sur votre compte iTunes et Kobo sera calcul\u00e9e et vous sera distribu\u00e9e automatiquement. \u00bb<\/p>\n<p>En cas de changement d\u2019adresse, assurez-vous d&rsquo;informer l&rsquo;Administrateur des R\u00e9clamations en fournissant votre nom complet, votre num\u00e9ro de r\u00e9clamation, vos anciennes coordonn\u00e9es, ainsi que vos nouvelles informations \u00e0 jour.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une action collective de livres \u00e9lectroniques qui a vis\u00e9 les revendeurs Google, Amazon, Sony, Kobo et iTunes s\u2019est conclue par un r\u00e8glement \u00e0 l\u2019amiable et donnera suite \u00e0 un d\u00e9dommagement &#8230; <a title=\"Livres \u00e9lectroniques : dernier d\u00e9lai pour se faire d\u00e9dommager\" class=\"read-more\" href=\"https:\/\/econostrum.info\/canada\/livres-electroniques-delai-dedommager\/\" aria-label=\"Read more about Livres \u00e9lectroniques : dernier d\u00e9lai pour se faire d\u00e9dommager\"> <\/a><\/p>\n","protected":false},"author":42,"featured_media":3474,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-3452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conso","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/posts\/3452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/comments?post=3452"}],"version-history":[{"count":0,"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/posts\/3452\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/media\/3474"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/media?parent=3452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/categories?post=3452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/tags?post=3452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}