{"id":2618,"date":"2024-07-16T12:09:14","date_gmt":"2024-07-16T16:09:14","guid":{"rendered":"https:\/\/econostrum.info\/canada\/?p=2618"},"modified":"2024-07-16T12:09:14","modified_gmt":"2024-07-16T16:09:14","slug":"canada-hausse-prix-lait-bebes","status":"publish","type":"post","link":"https:\/\/econostrum.info\/canada\/canada-hausse-prix-lait-bebes\/","title":{"rendered":"Canada : Pourquoi cette hausse spectaculaire des prix du lait maternis\u00e9 ?"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>L&rsquo;inflation alimentaire au <strong>Canada<\/strong> n\u2019a pas seulement touch\u00e9 les produits de base ou d\u2019\u00e9picerie destin\u00e9s aux consommateurs adultes, mais s\u2019est bien \u00e9tendue \u00e0 d&rsquo;autres articles destin\u00e9s \u00e0 d&rsquo;autres segments de consommateurs, notamment <strong>les b\u00e9b\u00e9s et les jeunes enfants.<\/strong><\/p>\n<p>Derni\u00e8rement, plusieurs parents se plaignent de <strong>l&rsquo;augmentation des prix des pr\u00e9parations pour nourrissons<\/strong>. Une situation d\u00e9peinte comme \u00ab\u00a0stressante\u00a0\u00bb par la majorit\u00e9 d&rsquo;entre eux, qui rencontrent des difficult\u00e9s \u00e0 acheter suffisamment de lait maternis\u00e9 pour leurs b\u00e9b\u00e9s.<\/p>\n<h2>Un nouveau d\u00e9fi pour les parents<\/h2>\n<p>En \u00e0 peine un semestre,<strong> une hausse \u00e9quivalente \u00e0 12 dollars<\/strong> a \u00e9t\u00e9 constat\u00e9e sur la bo\u00eete de lait maternis\u00e9 de la marque Similac. Une augmentation que les parents ont du mal \u00e0 accepter, \u00e9tant donn\u00e9 que <a href=\"https:\/\/econostrum.info\/canada\/menages-canadiens-preoccupes-finances\/\">la situation financi\u00e8re des m\u00e9nages au Canada<\/a> est d\u00e9j\u00e0 assez compliqu\u00e9e. C&rsquo;est dans ce contexte que Samantha Krobel, une m\u00e8re ontarienne, s\u2019est exprim\u00e9e aupr\u00e8s de Noovo Info pour d\u00e9noncer cette hausse des prix assez inattendue. \u00ab Nous payions 57,97 $ par bo\u00eete et nous utilisions environ trois bo\u00eetes par mois. Puis tout d\u2019un coup, en juin, le prix a grimp\u00e9 \u00e0 69,97 $ \u00bb, a-t-elle d\u00e9clar\u00e9. \u00ab Et ce n\u2019est pas seulement sa marque. J\u2019ai vu d&rsquo;autres marques augmenter \u00e9galement, mais il semble bien que Similac soit la pire \u00bb, a-t-elle ajout\u00e9.<\/p>\n<p>Selon les derniers chiffres avanc\u00e9s par Statistique Canada, le prix moyen de ces pr\u00e9parations pour nourrisson a bondi de <strong>30 % entre f\u00e9vrier 2022 et f\u00e9vrier 2024<\/strong>, tandis que d\u2019autres donn\u00e9es de la m\u00eame source montrent que ce co\u00fbt a augment\u00e9 de 10 % rien qu&rsquo;au cours des cinq premiers mois de l&rsquo;ann\u00e9e.<\/p>\n<h2>Quelles sont les raisons derri\u00e8re cette hausse sur le lait maternis\u00e9 ?<\/h2>\n<p>Selon les fabricants de ces bo\u00eetes de lait maternis\u00e9, c\u2019est<strong> l&rsquo;augmentation des co\u00fbts li\u00e9s \u00e0 la fabrication<\/strong> et \u00e0 la livraison du produit qui a entra\u00een\u00e9 cette hausse des prix. Abbott, le fabricant de la pr\u00e9paration pour nourrissons Similac, s\u2019est exprim\u00e9 sur le sujet : \u00ab Abbott s&rsquo;engage \u00e0 fournir des pr\u00e9parations pour nourrissons de haute qualit\u00e9. Nous comprenons la pression que la hausse des co\u00fbts exerce sur les familles, et c\u2019est pourquoi nous travaillons avec diligence pour g\u00e9rer les co\u00fbts des ingr\u00e9dients, de la fabrication et de la distribution des pr\u00e9parations pour nourrissons \u00bb, a d\u00e9clar\u00e9 l\u2019entreprise dans un communiqu\u00e9 transmis \u00e0 CTV News. \u00ab Les pr\u00e9parations pour nourrissons sont tr\u00e8s <strong>complexes \u00e0 produire et \u00e0 exporter.<\/strong> Il est donc n\u00e9cessaire d&rsquo;ajuster certains de nos co\u00fbts croissants pour servir les<strong> familles canadiennes<\/strong> \u00bb, a ajout\u00e9 le fabricant.<\/p>\n<p>Sylvain Charlebois, directeur du laboratoire d\u2019analyse agroalimentaire de l&rsquo;universit\u00e9 Dalhousie, affirme qu\u2019il n&rsquo;y a pas de <strong>p\u00e9nurie de ce produit \u00e0 l&rsquo;heure actuelle<\/strong>, mais que plusieurs facteurs, tels que les co\u00fbts de transport et les fluctuations mon\u00e9taires, contribuent \u00e0 <strong>la hausse des prix<\/strong>. \u00ab Les co\u00fbts de transport sont un autre probl\u00e8me, de m\u00eame que la monnaie. Il y a donc de multiples facteurs qui ont rendu ce produit plus cher \u00bb, a-t-il r\u00e9v\u00e9l\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; L&rsquo;inflation alimentaire au Canada n\u2019a pas seulement touch\u00e9 les produits de base ou d\u2019\u00e9picerie destin\u00e9s aux consommateurs adultes, mais s\u2019est bien \u00e9tendue \u00e0 d&rsquo;autres articles destin\u00e9s \u00e0 d&rsquo;autres segments &#8230; <a title=\"Canada : Pourquoi cette hausse spectaculaire des prix du lait maternis\u00e9 ?\" class=\"read-more\" href=\"https:\/\/econostrum.info\/canada\/canada-hausse-prix-lait-bebes\/\" aria-label=\"Read more about Canada : Pourquoi cette hausse spectaculaire des prix du lait maternis\u00e9 ?\"> <\/a><\/p>\n","protected":false},"author":35,"featured_media":2631,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-2618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conso","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/posts\/2618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/comments?post=2618"}],"version-history":[{"count":0,"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/posts\/2618\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/media\/2631"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/media?parent=2618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/categories?post=2618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/canada\/wp-json\/wp\/v2\/tags?post=2618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}