{"id":950,"date":"2024-04-01T16:07:39","date_gmt":"2024-04-01T14:07:39","guid":{"rendered":"https:\/\/econostrum.info\/belgique\/?p=950"},"modified":"2024-04-01T16:07:39","modified_gmt":"2024-04-01T14:07:39","slug":"date-de-aid-el-fitr-2024-belgique","status":"publish","type":"post","link":"https:\/\/econostrum.info\/belgique\/date-de-aid-el-fitr-2024-belgique\/","title":{"rendered":"\u00c0 Quelle date aura lieu l&rsquo;Aid-El-Fitr 2024 en Belgique ?"},"content":{"rendered":"<p><strong>L&rsquo;A\u00efd-El-Fitr est la f\u00eate c\u00e9l\u00e9br\u00e9e par la communaut\u00e9 musulmane \u00e0 la fin du mois de Ramadan, qui avait d\u00e9but\u00e9 le 10 mars en Belgique. La date de cette f\u00eate, comme celle du d\u00e9but du mois de Ramadan, doit \u00eatre confirm\u00e9e chaque ann\u00e9e par le Conseil des th\u00e9ologiens au Conseil musulman de Belgique.<\/strong><\/p>\n<p>Et pour cause, le nombre de jours du <a href=\"https:\/\/econostrum.info\/belgique\/mois-de-ramadan-belgique\/\">mois de Ramadan<\/a> peut varier d&rsquo;une ann\u00e9e \u00e0 l&rsquo;autre. Il se compose tant\u00f4t de 29 jours et tant\u00f4t de 30. Or, les musulmans ne peuvent rompre le je\u00fbne avant d&rsquo;avoir observ\u00e9 clairement le croissant lunaire. Cette observation, qui confirme officiellement l&rsquo;arriv\u00e9e de l&rsquo;A\u00efd-El-Fitr, a lieu chaque ann\u00e9e lors du 29e jour du 9\u1d49 mois du calendrier h\u00e9girien. Un jour particulier pour les musulmans, appel\u00e9 \u00ab la nuit du doute \u00bb, qui aura lieu le 8 avril 2024.<\/p>\n<h2>L&rsquo;A\u00efd-El-Fitr le 9 ou 10 avril<\/h2>\n<p>Quant \u00e0 la date de l&rsquo;A\u00efd-El-Fitr, celle-ci sera \u00e9tablie le 9 ou le 10 avril. Il s&rsquo;agit d&rsquo;une c\u00e9l\u00e9bration modeste au cours de laquelle les musulmans se rendent visite et se r\u00e9unissent autour d&rsquo;un repas traditionnel. \u00c0 l&rsquo;heure du caf\u00e9, un assortiment de g\u00e2teaux orientaux est dress\u00e9 sur la table pour accueillir les visiteurs. Selon la tradition, les plus jeunes doivent se d\u00e9placer chez leurs a\u00een\u00e9s. C&rsquo;est \u00e9galement l&rsquo;occasion de se r\u00e9concilier avec ses proches et de solidifier les liens familiaux. Cette f\u00eate est par ailleurs tr\u00e8s appr\u00e9ci\u00e9e par les enfants, qui re\u00e7oivent des v\u00eatements neufs pour l&rsquo;occasion, ainsi que des cadeaux.<\/p>\n<h2>Quel sera le montant de la Zakat El Fitr cette ann\u00e9e ?<\/h2>\n<p>La Zakat El Fitr\u00a0 est une donation offerte par les musulmans aux plus d\u00e9munis lors du dernier jour du mois sacr\u00e9. Il s&rsquo;agit d&rsquo;une aide offerte aux personnes dans le besoin afin de leur permettre de profiter d&rsquo;un bon repas lors de la f\u00eate de l&rsquo;A\u00efd-El-Fitr. Elle doit \u00eatre vers\u00e9e par le p\u00e8re de famille et son montant peut varier d&rsquo;une ann\u00e9e \u00e0 l&rsquo;autre en fonction de la composition du foyer. Cette ann\u00e9e, elle s&rsquo;\u00e9tablit \u00e0 7 euros par personne. Par cons\u00e9quent, pour une famille de 4 personnes, par exemple, elle atteint 28 euros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;A\u00efd-El-Fitr est la f\u00eate c\u00e9l\u00e9br\u00e9e par la communaut\u00e9 musulmane \u00e0 la fin du mois de Ramadan, qui avait d\u00e9but\u00e9 le 10 mars en Belgique. La date de cette f\u00eate, comme &#8230; <a title=\"\u00c0 Quelle date aura lieu l&rsquo;Aid-El-Fitr 2024 en Belgique ?\" class=\"read-more\" href=\"https:\/\/econostrum.info\/belgique\/date-de-aid-el-fitr-2024-belgique\/\" aria-label=\"Read more about \u00c0 Quelle date aura lieu l&rsquo;Aid-El-Fitr 2024 en Belgique ?\"> <\/a><\/p>\n","protected":false},"author":9,"featured_media":962,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/posts\/950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/comments?post=950"}],"version-history":[{"count":0,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/posts\/950\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/media\/962"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/media?parent=950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/categories?post=950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/tags?post=950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}