{"id":6541,"date":"2024-11-23T10:30:40","date_gmt":"2024-11-23T09:30:40","guid":{"rendered":"https:\/\/econostrum.info\/belgique\/?p=6541"},"modified":"2024-11-22T17:46:22","modified_gmt":"2024-11-22T16:46:22","slug":"amende-doudoune-conduite-en-hiver","status":"publish","type":"post","link":"https:\/\/econostrum.info\/belgique\/amende-doudoune-conduite-en-hiver\/","title":{"rendered":"Belgique : Pourquoi votre doudoune peut vous faire payer une amende en conduisant ?"},"content":{"rendered":"<p>Avec le froid et le givre qui s&rsquo;installent ces derniers jours en <strong>Belgique<\/strong>, il est hors de question de sortir de chez soi sans \u00eatre emmitoufl\u00e9 dans une grosse doudoune, une \u00e9charpe et encore moins sans porter de gants. Mais lorsqu&rsquo;il s&rsquo;agit de prendre sa voiture, tout cet \u00e9quipement encombrant risque de rendre la conduite plus compliqu\u00e9e, d\u2019autant plus qu\u2019une couche de verglas recouvre toutes les routes.<\/p>\n<p>Ce que les automobilistes ignorent, c\u2019est que porter des v\u00eatements tr\u00e8s \u00e9pais peut \u00eatre consid\u00e9r\u00e9 comme une<strong> infraction au code de la route<\/strong>. Pire encore, cela pourrait m\u00eame entra\u00eener <strong>le paiement d\u2019une amende<\/strong> dans certains cas.<\/p>\n<h3>Le confort thermique pourrait bien co\u00fbter une amende<\/h3>\n<p>Qui dit hiver, dit forc\u00e9ment porter des v\u00eatements chauds, notamment durant les matins o\u00f9 il fait particuli\u00e8rement froid. Dans ce cas, prendre le volant tout en \u00e9tant emmitoufl\u00e9 dans un gros manteau, avec une \u00e9charpe et des gants, peut para\u00eetre \u00eatre une tr\u00e8s bonne id\u00e9e. Mais ce n\u2019est toutefois pas le cas, car cela peut entra\u00eener une<a href=\"https:\/\/econostrum.info\/belgique\/automobilistes-belges-amende-mesure\/\"> amende pour le conducteur.<\/a><\/p>\n<p>Comment cela est-il possible ? Il suffit de jeter <strong>un coup d&rsquo;\u0153il \u00e0 l&rsquo;article 8.3 du code de la route<\/strong> pour trouver la r\u00e9ponse. En effet, il est stipul\u00e9 que tout conducteur doit \u00eatre en \u00e9tat de conduire, pr\u00e9senter les qualit\u00e9s physiques requises et poss\u00e9der les connaissances et l&rsquo;habilet\u00e9 n\u00e9cessaires.<\/p>\n<p>Certes, l&rsquo;article ne mentionne pas explicitement que le port de v\u00eatements \u00e9pais est interdit au volant, mais il est important de savoir que si les v\u00eatements en question <strong>emp\u00eachent l&rsquo;automobiliste de conduire correctement<\/strong>, cela peut constituer une infraction de troisi\u00e8me degr\u00e9.<\/p>\n<h3>Prendre soin de bien choisir ses v\u00eatements d&rsquo;hiver<\/h3>\n<p>Afin d\u2019\u00e9viter ce genre d\u2019inconv\u00e9nient, il est important de bien r\u00e9fl\u00e9chir aux v\u00eatements \u00e0 porter au volant. Dans le cas des gants, par exemple, cela signifie qu\u2019il faut s\u2019assurer d\u2019avoir suffisamment d&rsquo;adh\u00e9rence sur le volant. \u00ab Il existe des gants sp\u00e9ciaux sur le march\u00e9 pr\u00e9vus \u00e0 cet effet. <strong>Les conducteurs de voitures anciennes<\/strong> en portent souvent. Veillez \u00e9galement \u00e0 ce qu\u2019ils ne soient pas trop \u00e9pais, car cela peut aussi \u00eatre g\u00eanant \u00bb, a expliqu\u00e9 Stef Willems, porte-parole de Vias, l&rsquo;institut pour la s\u00e9curit\u00e9 routi\u00e8re.<\/p>\n<p>Les m\u00eames principes s&rsquo;appliquent au port d\u2019une veste au volant. Il faut donc s\u2019assurer d\u2019avoir <strong>suffisamment d\u2019espace pour bouger et effectuer les man\u0153uvres.<\/strong> En ce qui concerne les chaussures, le code de la route ne pr\u00e9voit rien de sp\u00e9cifique \u00e0 ce sujet. Tant que la conduite reste fluide et sans entrave, il est permis de porter n\u2019importe quel type de chaussures.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-weight: 400\">Prendre la route durant cette saison n\u2019est pas toujours une partie de plaisir. Pour se prot\u00e9ger du froid, de nombreux conducteurs emmitonnent leurs corps dans d&rsquo;\u00e9paisses couches de v\u00eatements. Il faudra toutefois garder bien en t\u00eate que le port de certaines pi\u00e8ces vestimentaires au volant peut tr\u00e8s bien entra\u00eener une amende.<\/span><\/p>\n","protected":false},"author":35,"featured_media":6587,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"class_list":["post-6541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilite","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/posts\/6541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/comments?post=6541"}],"version-history":[{"count":0,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/posts\/6541\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/media\/6587"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/media?parent=6541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/categories?post=6541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/tags?post=6541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}