{"id":112559,"date":"2026-07-14T13:00:00","date_gmt":"2026-07-14T11:00:00","guid":{"rendered":"https:\/\/econostrum.info\/belgique\/?p=112559"},"modified":"2026-07-14T11:22:20","modified_gmt":"2026-07-14T09:22:20","slug":"declaration-fiscale-calendrier-bouleverse","status":"publish","type":"post","link":"https:\/\/econostrum.info\/belgique\/declaration-fiscale-calendrier-bouleverse\/","title":{"rendered":"D\u00e9claration fiscale belge : le calendrier boulevers\u00e9 par une panne technique"},"content":{"rendered":"\n<p><strong>Les contribuables belges disposent de quelques jours suppl\u00e9mentaires pour envoyer leur d\u00e9claration fiscale 2026. Apr\u00e8s des probl\u00e8mes de connexion sur MyMinfin, le SPF Finances a repouss\u00e9 l\u2019\u00e9ch\u00e9ance initialement fix\u00e9e au 15 juillet. Le nouveau d\u00e9lai prend fin le 19 juillet 2026.<\/strong><\/p>\n\n\n\n<p>Les citoyens avaient normalement jusqu\u2019au mercredi 15 juillet pour remplir leur d\u00e9claration sur Tax-on-web. Ils pourront finalement effectuer cette d\u00e9marche jusqu\u2019au dimanche 19 juillet inclus. Cette prolongation concerne aussi les personnes qui souhaitent corriger ou compl\u00e9ter en ligne leur proposition de d\u00e9claration simplifi\u00e9e.<\/p>\n\n\n\n<p>Le SPF Finances a annonc\u00e9 ce report apr\u00e8s avoir constat\u00e9 que certains utilisateurs ne parvenaient pas \u00e0 se connecter correctement \u00e0 Tax-on-web depuis MyMinfin. La nouvelle \u00e9ch\u00e9ance a notamment \u00e9t\u00e9 confirm\u00e9e par <a href=\"https:\/\/www.rtbf.be\/article\/problemes-techniques-chez-taxonweb-le-delai-pour-rendre-sa-declaration-est-prolonge-jusqu-au-19-juillet-11756989\" target=\"_blank\" rel=\"noopener\">la RTBF<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-x wp-block-embed-x\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"fr\" dir=\"ltr\">Probl\u00e8mes techniques sur le site de d\u00e9claration d\u2019imp\u00f4ts : le SPF Finances annonce une bonne nouvelle <a href=\"https:\/\/t.co\/0MOOrQ1QuV\">https:\/\/t.co\/0MOOrQ1QuV<\/a><\/p>&mdash; RTL info (@rtlinfo) <a href=\"https:\/\/x.com\/rtlinfo\/status\/2076605561584378249?ref_src=twsrc%5Etfw\">July 13, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Un incident technique \u00e0 l\u2019origine du report<\/h2>\n\n\n\n<p>Les difficult\u00e9s ont commenc\u00e9 le vendredi pr\u00e9c\u00e9dant la date limite et se sont poursuivies durant le week-end. Une partie des contribuables n\u2019a donc pas pu consulter, modifier ou envoyer sa d\u00e9claration dans des conditions normales. Face \u00e0 cette situation, l\u2019administration fiscale a d\u00e9cid\u00e9 d\u2019accorder quatre jours suppl\u00e9mentaires.<\/p>\n\n\n\n<p>Le SPF Finances indique aussi poursuivre ses interventions sur ses applications num\u00e9riques afin de r\u00e9tablir un fonctionnement stable. Les contribuables qui avaient d\u00e9j\u00e0 envoy\u00e9 leur d\u00e9claration ne doivent accomplir aucune nouvelle d\u00e9marche, sauf s\u2019ils souhaitent encore la corriger avant la nouvelle \u00e9ch\u00e9ance.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qui est concern\u00e9 par la nouvelle date limite de la d\u00e9claration fiscale ?<\/h2>\n\n\n\n<p>Le report vise les d\u00e9clarations classiques d\u00e9pos\u00e9es en ligne ainsi que les propositions de d\u00e9claration simplifi\u00e9e modifi\u00e9es via MyMinfin. Les contribuables soumis \u00e0 un calendrier particulier, notamment en raison de revenus professionnels sp\u00e9cifiques ou \u00e9trangers, doivent v\u00e9rifier la date affich\u00e9e dans leur espace personnel. Certaines situations fiscales disposent d\u00e9j\u00e0 d\u2019un d\u00e9lai distinct.<\/p>\n\n\n\n<p>La date du 19 juillet ne concerne pas non plus les d\u00e9clarations papier, dont le calendrier suit d\u2019autres r\u00e8gles. M\u00eame avec cette prolongation, il reste pr\u00e9f\u00e9rable d\u2019envoyer sa <a href=\"https:\/\/econostrum.info\/belgique\/declaration-fiscale-2026-dates-limites\/\" target=\"_blank\" rel=\"noopener\">d\u00e9claration<\/a> avant les derni\u00e8res heures. Une forte affluence sur MyMinfin pourrait ralentir les connexions \u00e0 l\u2019approche de l\u2019\u00e9ch\u00e9ance.<\/p>\n\n\n\n<p>Avant la validation, les contribuables doivent relire leurs revenus, leurs charges d\u00e9ductibles, leurs d\u00e9penses donnant droit \u00e0 une r\u00e9duction fiscale et les informations relatives \u00e0 leur famille. Une fois la d\u00e9claration envoy\u00e9e, l\u2019accus\u00e9 de r\u00e9ception disponible dans <a href=\"https:\/\/www.minfin.fgov.be\/myminfin-web\/\" target=\"_blank\" rel=\"noopener\">MyMinfin<\/a> doit \u00eatre conserv\u00e9. Il confirme que le document a bien \u00e9t\u00e9 transmis avant la date limite.<\/p>\n\n\n\n<p>Le nouveau calendrier donne donc jusqu\u2019au 19 juillet 2026 aux personnes touch\u00e9es par les probl\u00e8mes techniques pour finaliser leur dossier fiscal en ligne.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La d\u00e9claration fiscale en ligne b\u00e9n\u00e9ficie d\u2019un d\u00e9lai suppl\u00e9mentaire apr\u00e8s des probl\u00e8mes techniques rencontr\u00e9s sur MyMinfin.<\/p>\n","protected":false},"author":22,"featured_media":111243,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[76],"class_list":["post-112559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiscalite","tag-impot","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/posts\/112559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/comments?post=112559"}],"version-history":[{"count":1,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/posts\/112559\/revisions"}],"predecessor-version":[{"id":112561,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/posts\/112559\/revisions\/112561"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/media\/111243"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/media?parent=112559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/categories?post=112559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/tags?post=112559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}