{"id":109623,"date":"2026-02-06T08:56:57","date_gmt":"2026-02-06T07:56:57","guid":{"rendered":"https:\/\/econostrum.info\/belgique\/?p=109623"},"modified":"2026-02-06T08:57:04","modified_gmt":"2026-02-06T07:57:04","slug":"greve-des-bus-tec-perturbations-massives","status":"publish","type":"post","link":"https:\/\/econostrum.info\/belgique\/greve-des-bus-tec-perturbations-massives\/","title":{"rendered":"Gr\u00e8ve des bus TEC : perturbations massives ce vendredi, quand le trafic sera-t-il r\u00e9tabli ?"},"content":{"rendered":"\n<p><strong>Ce vendredi, les voyageurs du r\u00e9seau TEC doivent faire face \u00e0 de nouvelles perturbations importantes. Les assembl\u00e9es du personnel, organis\u00e9es pour d\u00e9cider de la suite du mouvement, continuent d\u2019affecter gravement le trafic. Le r\u00e9seau des bus LeTec reste en grande partie paralys\u00e9, et la situation risque de se prolonger tant que le conflit avec la direction n\u2019est pas r\u00e9solu.<\/strong><\/p>\n\n\n\n<p>A Li\u00e8ge-Verviers, ce sont 113 lignes qui sont \u00e0 l\u2019arr\u00eat ce matin, y compris sur les lignes importantes comme le tram et le BUSWAY 2. Seules 82 lignes assurent un service normal, tandis que 10 lignes fonctionnent avec des fr\u00e9quences r\u00e9duites, affect\u00e9es par la suppression de plusieurs voyages. Les usagers se retrouvent dans une situation de grande difficult\u00e9, n&rsquo;ayant souvent que peu d&rsquo;alternatives pour se d\u00e9placer.<\/p>\n\n\n\n<p>La situation est similaire \u00e0 Charleroi, o\u00f9 les bus et le m\u00e9tro restent \u00e0 l\u2019arr\u00eat. Toutefois, 13 lignes circulent encore, bien qu&rsquo;avec des itin\u00e9raires limit\u00e9s, indique <a href=\"https:\/\/www.rtbf.be\/article\/greve-des-bus-tec-le-reseau-toujours-tres-perturbe-avant-les-assemblees-du-personnel-11674800\" target=\"_blank\" rel=\"noopener\">la RTBF<\/a>. La gr\u00e8ve \u00e9tant toujours en cours, il semble que le trafic reste fortement perturb\u00e9, les syndicats ayant d\u00e9cid\u00e9 de prolonger le mouvement apr\u00e8s l&rsquo;assembl\u00e9e de ce vendredi matin. L\u2019absence de solution rapide de la part de la direction et l\u2019intensification des discussions semblent prolonger cette situation de crise.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Perturbations dans d&rsquo;autres r\u00e9gions et impact sur le transport scolaire<\/h2>\n\n\n\n<p>En dehors des grandes agglom\u00e9rations de Li\u00e8ge et Charleroi, le reste du r\u00e9seau TEC subit \u00e9galement des perturbations. A Letec Hainaut, 35 lignes sont limit\u00e9es ou compl\u00e8tement supprim\u00e9es, avec seulement 17 lignes qui circulent normalement. En revanche, les lignes de transport scolaire et le transport \u00e0 la demande, qui sont essentiels pour de nombreux \u00e9l\u00e8ves et \u00e9tudiants, ne sont pas affect\u00e9s par le mouvement de gr\u00e8ve.<\/p>\n\n\n\n<p>Les provinces de Namur et du Luxembourg n&rsquo;ont pas encore fait \u00e9tat de perturbations majeures, mais des \u00ab l\u00e9g\u00e8res perturbations \u00bb sont \u00e0 pr\u00e9voir. Cela t\u00e9moigne du caract\u00e8re \u00e9tendu du conflit, qui touche progressivement plusieurs zones du pays. Quant au Brabant wallon, la situation devrait \u00e9galement rester tendue, avec des perturbations \u00ab importantes \u00bb attendues tout au long de la journ\u00e9e.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"fr\" dir=\"ltr\">La gr\u00e8ve du Tec se poursuit : m\u00e9tros, trams et bus impact\u00e9s, le point sur les perturbations <a href=\"https:\/\/t.co\/S9CJlwcssv\">https:\/\/t.co\/S9CJlwcssv<\/a><\/p>&mdash; Le Soir (@lesoir) <a href=\"https:\/\/twitter.com\/lesoir\/status\/2019663861264048192?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">February 6, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Les raisons de la gr\u00e8ve des TEC et les perspectives d\u2019une reprise du service<\/h2>\n\n\n\n<p><a href=\"https:\/\/econostrum.info\/belgique\/greve-des-bus-tec\/\" target=\"_blank\" rel=\"noopener\">La gr\u00e8ve des bus TEC<\/a> trouve son origine dans une contestation contre des mesures \u00e9conomiques propos\u00e9es par la direction de l\u2019entreprise. Ces mesures, qui incluent des suppressions de postes et une r\u00e9organisation des services, ont provoqu\u00e9 une vive r\u00e9action des syndicats, qui r\u00e9clament un gel de ces r\u00e9formes et une r\u00e9vision des conditions de travail.<\/p>\n\n\n\n<p>Les syndicats ont d\u00e9j\u00e0 indiqu\u00e9 qu\u2019ils poursuivraient le mouvement tant qu\u2019aucune solution satisfaisante n\u2019est trouv\u00e9e avec la direction. Les assembl\u00e9es de ce vendredi matin \u00e9taient donc cruciales pour d\u00e9terminer l\u2019orientation du mouvement dans les jours \u00e0 venir. Si aucune issue rapide n\u2019est trouv\u00e9e, les perturbations risquent de s&rsquo;intensifier et de durer encore plusieurs jours, entra\u00eenant des difficult\u00e9s accrues pour les usagers et les travailleurs qui d\u00e9pendent du transport public.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La gr\u00e8ve des bus TEC se poursuit ce vendredi, provoquant de fortes perturbations sur le r\u00e9seau. La situation reste incertaine avec des assembl\u00e9es du personnel.<\/p>\n","protected":false},"author":22,"featured_media":109625,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"class_list":["post-109623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilite","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/posts\/109623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/comments?post=109623"}],"version-history":[{"count":1,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/posts\/109623\/revisions"}],"predecessor-version":[{"id":109626,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/posts\/109623\/revisions\/109626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/media\/109625"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/media?parent=109623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/categories?post=109623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/tags?post=109623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}