{"id":108073,"date":"2025-11-23T10:31:00","date_gmt":"2025-11-23T09:31:00","guid":{"rendered":"https:\/\/econostrum.info\/belgique\/?p=108073"},"modified":"2025-11-23T09:51:22","modified_gmt":"2025-11-23T08:51:22","slug":"appel-a-la-greve-dans-les-commerces","status":"publish","type":"post","link":"https:\/\/econostrum.info\/belgique\/appel-a-la-greve-dans-les-commerces\/","title":{"rendered":"Appel \u00e0 la gr\u00e8ve dans les commerces Belges : les f\u00eates de fin d&rsquo;ann\u00e9e en p\u00e9ril ?"},"content":{"rendered":"\n<p><strong>Les syndicats du secteur du commerce ont d\u00e9pos\u00e9 un pr\u00e9avis de gr\u00e8ve, mena\u00e7ant de perturber les festivit\u00e9s de fin d&rsquo;ann\u00e9e si leurs revendications ne sont pas prises en compte. Ce pr\u00e9avis fait suite \u00e0 un appel \u00e0 la gr\u00e8ve g\u00e9n\u00e9rale pr\u00e9vu pour le 26 novembre 2025 et co\u00efncide avec une r\u00e9union de n\u00e9gociation pr\u00e9vue le 2 d\u00e9cembre entre les syndicats et le patronat.<\/strong><\/p>\n\n\n\n<p>Les syndicats Setca, CNE et CGSLB ont clairement indiqu\u00e9 que la situation devait \u00e9voluer avant la fin du pr\u00e9avis, soit le 4 d\u00e9cembre. Si des solutions ne sont pas trouv\u00e9es d&rsquo;ici l\u00e0, les f\u00eates de fin d&rsquo;ann\u00e9e dans le secteur du commerce pourraient \u00eatre gravement perturb\u00e9es, mettant en p\u00e9ril les conditions de travail et les emplois pour de nombreux salari\u00e9s. Cette gr\u00e8ve pourrait toucher divers aspects du commerce, de la distribution en magasin \u00e0 la logistique, notamment pendant une p\u00e9riode cruciale pour les commer\u00e7ants, d\u00e9taille <a href=\"https:\/\/www.sudinfo.be\/id1071790\/article\/2025-11-22\/les-syndicats-du-commerce-deposent-un-preavis-de-greve-soit-des-solutions-sont\" target=\"_blank\" rel=\"noopener\">Sudinfo<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"fr\" dir=\"ltr\">Les syndicats du commerce d\u00e9posent un pr\u00e9avis de gr\u00e8ve : &quot;soit des solutions sont trouv\u00e9es, soit les f\u00eates seront mises \u00e0 mal&quot; <a href=\"https:\/\/t.co\/okLGxsHOmd\">https:\/\/t.co\/okLGxsHOmd<\/a><\/p>&mdash; DH les Sports + (@ladh) <a href=\"https:\/\/twitter.com\/ladh\/status\/1992230595288563820?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">November 22, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Quelles sont les revendications du secteur du commerce ?<\/h2>\n\n\n\n<p>Leurs revendications sont ambitieuses. Les syndicats se battent contre plusieurs projets qui, selon eux, risquent d\u2019aggraver les conditions de travail des employ\u00e9s. Parmi les principales inqui\u00e9tudes figurent l&rsquo;annualisation du temps de travail, une mesure qui permettrait aux employeurs de moduler les horaires des employ\u00e9s tout au long de l&rsquo;ann\u00e9e, ainsi que l&rsquo;extension du travail de nuit et l\u2019ouverture dominicale. Ces mesures seraient per\u00e7ues comme des atteintes \u00e0 la qualit\u00e9 de vie des travailleurs, d&rsquo;autant plus que ces derniers font face \u00e0 des rythmes de travail d\u00e9j\u00e0 tr\u00e8s contraignants.<\/p>\n\n\n\n<p>Les syndicats exigent aussi une harmonisation des commissions paritaires entre les diff\u00e9rents magasins et cha\u00eenes de distribution. Ils pointent \u00e9galement du doigt des probl\u00e8mes r\u00e9currents dans le secteur, tels que le non-respect des lois par certains employeurs, qui laissent des pratiques d\u00e9r\u00e9gul\u00e9es se d\u00e9velopper. De plus, le recours accru aux contrats pr\u00e9caires est un autre facteur de m\u00e9contentement. Les syndicats estiment que cette pr\u00e9carisation rend difficile toute n\u00e9gociation pour des am\u00e9liorations durables des conditions de travail.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les f\u00eates de fin d&rsquo;ann\u00e9e risquent d&rsquo;\u00eatre perturb\u00e9es par cette gr\u00e8ve<\/h2>\n\n\n\n<p>La gr\u00e8ve pourrait avoir un impact majeur sur le secteur du commerce, qui est l&rsquo;un des plus importants de l&rsquo;\u00e9conomie. <a href=\"https:\/\/econostrum.info\/belgique\/noel-les-prix-des-sapins-flambent\/\" target=\"_blank\" rel=\"noopener\">Les f\u00eates de fin d\u2019ann\u00e9e<\/a>, p\u00e9riode de forte consommation, risquent d&rsquo;\u00eatre particuli\u00e8rement affect\u00e9es, non seulement en termes de chiffre d&rsquo;affaires, mais aussi de relations entre employeurs et employ\u00e9s. Les syndicats ont averti que si leurs demandes ne sont pas prises en compte, l&rsquo;ann\u00e9e 2025 pourrait se terminer sur une note conflictuelle, marqu\u00e9e par des tensions dans un secteur d\u00e9j\u00e0 sous pression.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un pr\u00e9avis de gr\u00e8ve a \u00e9t\u00e9 d\u00e9pos\u00e9 dans le commerce, mena\u00e7ant de perturber les f\u00eates de fin d&rsquo;ann\u00e9e si des solutions ne sont pas rapidement trouv\u00e9es.<\/p>\n","protected":false},"author":22,"featured_media":108075,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-108073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/posts\/108073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/comments?post=108073"}],"version-history":[{"count":1,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/posts\/108073\/revisions"}],"predecessor-version":[{"id":108076,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/posts\/108073\/revisions\/108076"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/media\/108075"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/media?parent=108073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/categories?post=108073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/tags?post=108073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}