{"id":104982,"date":"2025-07-03T08:50:00","date_gmt":"2025-07-03T06:50:00","guid":{"rendered":"https:\/\/econostrum.info\/belgique\/?p=104982"},"modified":"2025-07-02T16:58:40","modified_gmt":"2025-07-02T14:58:40","slug":"fournisseurs-energie-changement-belges","status":"publish","type":"post","link":"https:\/\/econostrum.info\/belgique\/fournisseurs-energie-changement-belges\/","title":{"rendered":"Fournisseurs d&rsquo;\u00e9nergie : un changement majeur attend les Belges en 2026"},"content":{"rendered":"\n<p>\u00c0 partir de janvier 2026, un grand bouleversement va transformer le service client des fournisseurs d\u2019\u00e9nergie en Belgique. En effet, la commission de l\u2019\u00c9nergie de la Chambre a r\u00e9cemment approuv\u00e9 une proposition de loi de Vooruit qui impose de nouvelles r\u00e8gles concernant l&rsquo;accessibilit\u00e9 des services clients.&nbsp;<\/p>\n\n\n\n<p>Ce changement a pour but de garantir une meilleure communication entre les consommateurs et leurs fournisseurs d\u2019\u00e9nergie, particuli\u00e8rement pour les personnes les plus vuln\u00e9rables ou ayant des comp\u00e9tences num\u00e9riques limit\u00e9es. Dans un contexte o\u00f9 la transparence et l\u2019accessibilit\u00e9 sont de plus en plus attendues, cette r\u00e9forme devrait r\u00e9pondre \u00e0 des besoins de base encore trop souvent ignor\u00e9s par les fournisseurs d&rsquo;\u00e9nergie.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Des services clients accessibles et r\u00e9actifs<\/strong><\/h2>\n\n\n\n<p>\u00c0 partir de 2026, tous les <a href=\"https:\/\/econostrum.info\/belgique\/reconduction-tacite-contrat-energie\/\" data-type=\"post\" data-id=\"4004\">fournisseurs d\u2019\u00e9nergie <\/a>devront offrir un service client disponible pendant les heures de bureau, soit entre 9h et 17h, et cela par t\u00e9l\u00e9phone et par e-mail. Cette obligation d\u00e9coule de la proposition de loi port\u00e9e par Oskar Seuntjens, chef de groupe du parti politique Vooruit, indique <a href=\"https:\/\/www.sudinfo.be\/id1013409\/article\/2025-07-01\/grand-changement-partir-de-2026-le-services-client-des-fournisseurs-denergie\" target=\"_blank\" rel=\"noopener\">Sudinfo<\/a>. Actuellement, de nombreux consommateurs sont redirig\u00e9s vers des outils num\u00e9riques comme des chatbots ou des questionnaires en ligne, ce qui peut se r\u00e9v\u00e9ler particuli\u00e8rement contraignant pour les personnes ayant des difficult\u00e9s avec les technologies. Pour ces groupes, qui incluent des personnes \u00e2g\u00e9es ou celles en situation de pr\u00e9carit\u00e9, l&rsquo;acc\u00e8s \u00e0 un interlocuteur humain reste essentiel pour r\u00e9soudre efficacement leurs probl\u00e8mes.<\/p>\n\n\n\n<p>La l\u00e9gislation en vigueur exige d\u00e9j\u00e0 un service client \u00ab\u00a0accessible et honn\u00eate\u00a0\u00bb, mais dans la pratique, beaucoup de clients se trouvent frustr\u00e9s par les r\u00e9ponses automatiques et les services num\u00e9riques souvent insuffisants. C\u2019est cette situation qui a pouss\u00e9 les l\u00e9gislateurs \u00e0 agir. La loi vise donc \u00e0 rendre ces services plus humains et plus facilement accessibles, en garantissant que les consommateurs puissent toujours parler \u00e0 un conseiller par t\u00e9l\u00e9phone ou recevoir une r\u00e9ponse par e-mail pendant les horaires de bureau.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Des contrats ajust\u00e9s aux nouvelles r\u00e8gles<\/strong><\/h2>\n\n\n\n<p>En plus de garantir une accessibilit\u00e9 en heures de bureau, cette r\u00e9forme introduit \u00e9galement une clause de rappel obligatoire pour les<a href=\"https:\/\/econostrum.info\/belgique\/baisse-contrats-energie-fixes-belgique\/\" data-type=\"post\" data-id=\"101508\"> contrats d\u2019\u00e9nergie<\/a>. Concr\u00e8tement, les clients auront la possibilit\u00e9 d\u2019opter pour un contrat qui pr\u00e9voit exclusivement un contact num\u00e9rique avec le service client. Toutefois, cette option devra \u00eatre valid\u00e9e par un consentement explicite du client. Si le consommateur rencontre un probl\u00e8me, il pourra appeler l&rsquo;assistance t\u00e9l\u00e9phonique, et le fournisseur aura deux jours ouvrables pour r\u00e9pondre \u00e0 la demande.<\/p>\n\n\n\n<p>Le projet de loi a \u00e9t\u00e9 largement soutenu, bien que l\u2019Open Vld ait vot\u00e9 contre. L\u2019objectif est d\u2019appliquer ces nouvelles r\u00e8gles \u00e0 partir de janvier 2026, mais uniquement pour les nouveaux contrats d\u2019\u00e9nergie. En ce qui concerne les contrats d\u00e9j\u00e0 existants, ils devront s&rsquo;adapter \u00e0 ces exigences lors de leur renouvellement. Cette mesure vise \u00e0 am\u00e9liorer l\u2019exp\u00e9rience client dans le secteur de l\u2019\u00e9nergie, un domaine o\u00f9 les clients se plaignent fr\u00e9quemment de difficult\u00e9s d&rsquo;acc\u00e8s et de r\u00e9activit\u00e9 des services apr\u00e8s-vente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Une avanc\u00e9e pour l\u2019inclusion num\u00e9rique<\/strong><\/h2>\n\n\n\n<p>L\u2019une des principales raisons de cette r\u00e9forme est de prot\u00e9ger les consommateurs vuln\u00e9rables, notamment ceux qui manquent de comp\u00e9tences num\u00e9riques. En effet, l\u2019orientation vers des outils automatis\u00e9s comme les chatbots ou les formulaires en ligne ne r\u00e9pond pas aux besoins de toutes les cat\u00e9gories de la population, surtout pour ceux qui ne sont pas \u00e0 l\u2019aise avec la technologie. En rendant obligatoire l\u2019acc\u00e8s au service client par t\u00e9l\u00e9phone et par e-mail, la r\u00e9forme cherche \u00e0 garantir une prise en charge rapide et adapt\u00e9e, en particulier pour les clients plus \u00e2g\u00e9s ou moins familiers avec les outils num\u00e9riques.<\/p>\n\n\n\n<p>De plus, cette r\u00e9forme s\u2019inscrit dans un cadre plus large de transformation num\u00e9rique des services publics, o\u00f9 l\u2019objectif est d\u2019assurer une meilleure \u00e9quit\u00e9 d\u2019acc\u00e8s aux services essentiels. Dans un contexte o\u00f9 les enjeux \u00e9nerg\u00e9tiques et \u00e9conomiques sont particuli\u00e8rement sensibles, cette r\u00e9forme pourrait am\u00e9liorer l&rsquo;image des fournisseurs d\u2019\u00e9nergie tout en renfor\u00e7ant la confiance des consommateurs.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e8s janvier 2026, les fournisseurs d&rsquo;\u00e9nergie en Belgique devront adapter leur service client aux nouvelles exigences l\u00e9gislatives, garantissant un acc\u00e8s humain et direct aux consommateurs pendant les heures de bureau.<\/p>\n","protected":false},"author":35,"featured_media":103462,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,25],"tags":[],"class_list":["post-104982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energie","category-conso","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/posts\/104982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/comments?post=104982"}],"version-history":[{"count":1,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/posts\/104982\/revisions"}],"predecessor-version":[{"id":104984,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/posts\/104982\/revisions\/104984"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/media\/103462"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/media?parent=104982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/categories?post=104982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/belgique\/wp-json\/wp\/v2\/tags?post=104982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}