{"id":5421,"date":"2024-11-06T14:42:53","date_gmt":"2024-11-06T13:42:53","guid":{"rendered":"https:\/\/econostrum.info\/algerie\/?p=5421"},"modified":"2024-11-06T14:42:53","modified_gmt":"2024-11-06T13:42:53","slug":"algerie-poste-met-en-garde-escroqueries","status":"publish","type":"post","link":"https:\/\/econostrum.info\/algerie\/algerie-poste-met-en-garde-escroqueries\/","title":{"rendered":"Fausses pages \u00e9lectroniques et SMS frauduleux : Alg\u00e9rie Poste met en garde ses clients contre les escroqueries"},"content":{"rendered":"<p><strong>Les escroqueries sur Internet sont monnaie courante. Des individus peu scrupuleux n&rsquo;h\u00e9sitent pas \u00e0 mettre en \u0153uvre plusieurs formes d&rsquo;arnaques pour voler des personnes vuln\u00e9rables. Les clients d&rsquo;Alg\u00e9rie Poste sont nombreux \u00e0 \u00eatre victimes de ces escrocs.<\/strong><\/p>\n<p>L&rsquo;entreprise, consciente du probl\u00e8me, a alert\u00e9 ses clients pour qu&rsquo;ils soient vigilants. En effet, la direction g\u00e9n\u00e9rale d\u2019Alg\u00e9rie Poste (AP) a mis en garde ses clients, dans un communiqu\u00e9 diffus\u00e9 le 5 novembre, contre des escrocs qui diffusent, en son nom, de fausses pages \u00e9lectroniques et des SMS frauduleux.<\/p>\n<p>\u00ab Alg\u00e9rie Poste appelle ses clients \u00e0 la plus grande vigilance face \u00e0 des pages \u00e9lectroniques et des SMS frauduleux. Ces imposteurs tentent de tromper les clients d\u2019AP en diffusant des informations mensong\u00e8res sous le nom de l\u2019entreprise \u00e0 des fins d\u2019escroquerie \u00bb, indique le communiqu\u00e9.<\/p>\n<p>Pour \u00e9viter de tomber dans le pi\u00e8ge des arnaqueurs, l&rsquo;entreprise \u00ab demande \u00e0 ses clients de faire preuve de la plus grande vigilance et de ne pas interagir avec ces contenus trompeurs \u00bb. Elle recommande \u00e0 ceux qui utilisent ses services \u00ab de ne jamais fournir d\u2019informations sensibles, telles que les identifiants de comptes postaux et encore les informations li\u00e9es \u00e0 la carte Edahabia \u00bb.<\/p>\n<h2>Alg\u00e9rie Poste veut sensibiliser ses clients<\/h2>\n<p>\u00ab <a href=\"https:\/\/econostrum.info\/algerie\/transfert-de-fonds-algerie-poste-operateurs-etrangers\/\" target=\"_blank\" rel=\"noopener\">Les seules applications<\/a> officielles sont BaridiMob et ECCP, et pour la communication par SMS, l\u2019identifiant \u00ab\u00a0ALG Poste\u00a0\u00bb est l\u2019unique exp\u00e9diteur \u00bb, rappelle la direction de l&rsquo;entreprise qui souligne que \u00ab dans le but de sensibiliser davantage ses clients, Alg\u00e9rie Poste a lanc\u00e9 une vaste campagne de sensibilisation, du 24 au 26 septembre 2024, sous le slogan \u00ab\u00a0En toute s\u00e9curit\u00e9, votre s\u00e9curit\u00e9 est notre priorit\u00e9\u00a0\u00bb \u00bb.<\/p>\n<p>\u00ab Cette initiative vise \u00e0 renforcer la culture de l\u2019utilisation s\u00e9curis\u00e9e des services de paiement, notamment la carte Edahabia et l\u2019application BaridiMob \u00bb, souligne Alg\u00e9rie Poste dans son communiqu\u00e9, en ajoutant que \u00ab guider les utilisateurs vers des pratiques s\u00e9curis\u00e9es, afin de les pr\u00e9munir contre les fraudes \u00e9lectroniques \u00bb fait \u00e9galement partie de ses objectifs.<\/p>\n<p><a href=\"https:\/\/www.poste.dz\/\" target=\"_blank\" rel=\"noopener\">Alg\u00e9rie Poste<\/a> \u00ab se r\u00e9serve le droit d\u2019engager des poursuites judiciaires \u00e0 l\u2019encontre de toute personne physique ou morale impliqu\u00e9e dans l\u2019usage frauduleux de ses applications ou services \u00bb, conclut le communiqu\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 l&rsquo;heure de la num\u00e9risation, les escroqueries sur la toile sont de plus en plus fr\u00e9quentes. Des individus peu scrupuleux\u00a0 n&rsquo;h\u00e9sitent pas \u00e0 mettre en \u0153uvre plusieurs formes de subterfuges pour arnaquer les citoyens. Alg\u00e9rie Poste a mis en garde ses clients et les a appel\u00e9s \u00e0 \u00eatre vigilants contre ce ph\u00e9nom\u00e8ne.<\/p>\n","protected":false},"author":5,"featured_media":5426,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5421","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/5421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/comments?post=5421"}],"version-history":[{"count":0,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/5421\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media\/5426"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media?parent=5421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/categories?post=5421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/tags?post=5421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}