{"id":5186,"date":"2024-10-20T14:58:13","date_gmt":"2024-10-20T13:58:13","guid":{"rendered":"https:\/\/econostrum.info\/algerie\/?p=5186"},"modified":"2024-10-20T14:58:13","modified_gmt":"2024-10-20T13:58:13","slug":"plf-2025-financements-exterieurs","status":"publish","type":"post","link":"https:\/\/econostrum.info\/algerie\/plf-2025-financements-exterieurs\/","title":{"rendered":"PLF 2025 : facilitation des financements ext\u00e9rieurs"},"content":{"rendered":"<p><strong>Le projet de la loi de finances (PLF 2025) a \u00e9t\u00e9 approuv\u00e9 en Conseil des ministres et sera soumis au Parlement au d\u00e9but du mois de novembre. Ce projet de loi pr\u00e9voit de faciliter le financement des \u00ab projets d\u2019int\u00e9r\u00eat national \u00bb.<\/strong><\/p>\n<p>Le PLF 2025 accorde un grand int\u00e9r\u00eat au financement ext\u00e9rieur. Il propose une modification de l\u2019article 108 de la loi n\u00b0 19-14 du 11 d\u00e9cembre 2019 portant la loi de finances de 2020 afin de faciliter ce genre de financement. \u00ab Le financement de projets d\u2019int\u00e9r\u00eat national peut \u00eatre assur\u00e9 par des institutions financi\u00e8res internationales, bilat\u00e9rales ou multilat\u00e9rales, ainsi que par tout autre partenaire financier, sous r\u00e9serve de l\u2019autorisation pr\u00e9alable du Conseil des ministres. Sont du ressort exclusif du minist\u00e8re des Finances, toutes actions portant sur la recherche de financement au profit des projets d\u2019int\u00e9r\u00eat national, l\u2019identification des bailleurs de fonds potentiels, de m\u00eame que l\u2019introduction de requ\u00eates aupr\u00e8s de ces derniers \u00bb, peut-on lire dans l\u2019article 196 du PLF qui modifie l\u2019article 108.<\/p>\n<p>\u00ab Les modalit\u00e9s d\u2019application du pr\u00e9sent article sont pr\u00e9cis\u00e9es, par arr\u00eat\u00e9 du <a href=\"https:\/\/www.mf.gov.dz\/index.php\/fr\/\" target=\"_blank\" rel=\"noopener\">ministre charg\u00e9 des Finances<\/a> \u00bb, pr\u00e9cise le texte du projet de loi de finances 2025. \u00ab L&rsquo;article initial, qui restreint le financement aux projets dits \u00ab strat\u00e9giques et structurants \u00bb, s\u2019av\u00e8re trop complexe dans sa mise en \u0153uvre, en raison des interpr\u00e9tations vari\u00e9es de ces termes selon les secteurs et les priorit\u00e9s des diff\u00e9rents acteurs. L\u2019absence de d\u00e9finition claire de ce qui constitue un projet \u00ab strat\u00e9gique \u00bb ou \u00ab structurant \u00bb peut cr\u00e9er des divergences et retarder l\u2019approbation des financements n\u00e9cessaires pour des projets d\u2019envergure nationale \u00bb, explique le gouvernement.<\/p>\n<p>\u00ab Afin de lever ces obstacles et de rendre le dispositif plus efficace et op\u00e9rationnel, il est propos\u00e9 de simplifier la disposition en se r\u00e9f\u00e9rant \u00e0 des \u00ab projets d\u2019int\u00e9r\u00eat national \u00bb. Cette formulation plus large et moins sujette \u00e0 interpr\u00e9tation permet de s\u00e9lectionner des projets non pas en fonction d\u2019int\u00e9r\u00eats ponctuels ou sectoriels, mais en fonction de leur contribution \u00e0 l\u2019int\u00e9r\u00eat national, c\u2019est-\u00e0-dire \u00e0 leur capacit\u00e9 \u00e0 dynamiser l\u2019\u00e9conomie, \u00e0 renforcer les infrastructures, et \u00e0 am\u00e9liorer les conditions de vie des citoyens \u00bb, justifie encore le m\u00eame texte.<\/p>\n<h2>Le financement ext\u00e9rieur, bien encadr\u00e9, ne remet en aucune mani\u00e8re en question la souverainet\u00e9 du pays, selon le PLF 2025<\/h2>\n<p>Le gouvernement compte ainsi \u00ab inclure une plus grande diversit\u00e9 de partenaires financiers, en ouvrant la possibilit\u00e9 de recours non seulement aux institutions financi\u00e8res internationales, mais aussi aux institutions bilat\u00e9rales et multilat\u00e9rales, ainsi qu\u2019\u00e0 d\u2019autres partenaires financiers, tels que les partenariats public-priv\u00e9 (PPP), ou encore les m\u00e9canismes de financement innovants \u00bb. \u00ab Cette ouverture est cruciale pour garantir un acc\u00e8s \u00e9largi aux sources de financement, notamment dans un contexte mondial o\u00f9 les options de financement se diversifient de plus en plus \u00bb, souligne le texte.<\/p>\n<p>Il faut dire que pour avoir acc\u00e8s \u00e0 ces financements, le texte pr\u00e9cise que cela est assujetti \u00e0 \u00ab la n\u00e9cessit\u00e9 d\u2019une autorisation pr\u00e9alable des autorit\u00e9s comp\u00e9tentes, assurant ainsi un contr\u00f4le appropri\u00e9 des engagements financiers pris au nom de l\u2019\u00c9tat. \u00bb. \u00ab Ce changement s\u2019inscrit dans une d\u00e9marche visant \u00e0 accro\u00eetre l\u2019efficacit\u00e9 et la transparence du recours aux financements ext\u00e9rieurs, tout en garantissant une souplesse et une adaptabilit\u00e9 aux besoins r\u00e9els du pays \u00bb, indique le texte.<\/p>\n<p>\u00ab Il est important de souligner que le recours au financement ext\u00e9rieur bien encadr\u00e9 ne remet en aucune mani\u00e8re en question la souverainet\u00e9 du pays sur ses choix \u00e9conomiques. Les projets \u00e0 financer seront identifi\u00e9s en fonction des priorit\u00e9s nationales, et chaque d\u00e9cision de financement restera sous le contr\u00f4le exclusif des autorit\u00e9s nationales \u00bb, conclut le <a href=\"https:\/\/econostrum.info\/algerie\/taxe-carburant-tunisie-montant-plf-2025\/\" target=\"_blank\" rel=\"noopener\">PLF 2025<\/a> concernant ce sujet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Approuv\u00e9 en Conseil des ministres et sera prochainement soumis au Parlement, le projet de la loi de finances 2025 pr\u00e9voit de faciliter le financement ext\u00e9rieur des \u00ab projets d\u2019int\u00e9r\u00eat national \u00bb.<\/p>\n","protected":false},"author":5,"featured_media":5188,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/5186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/comments?post=5186"}],"version-history":[{"count":0,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/5186\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media\/5188"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media?parent=5186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/categories?post=5186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/tags?post=5186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}