{"id":4124,"date":"2024-08-11T12:30:30","date_gmt":"2024-08-11T11:30:30","guid":{"rendered":"https:\/\/econostrum.info\/algerie\/?p=4124"},"modified":"2024-08-11T12:30:30","modified_gmt":"2024-08-11T11:30:30","slug":"argent-de-linformel-inclusion-financiere","status":"publish","type":"post","link":"https:\/\/econostrum.info\/algerie\/argent-de-linformel-inclusion-financiere\/","title":{"rendered":"L&rsquo;argent de l&rsquo;informel repr\u00e9sente 34 % de la masse mon\u00e9taire en Alg\u00e9rie : les projets lanc\u00e9s pour une meilleure inclusion financi\u00e8re"},"content":{"rendered":"<p><strong>Le secteur de l&rsquo;informel repr\u00e9sente une partie importante de l&rsquo;\u00e9conomie en Alg\u00e9rie. Les sommes d&rsquo;argent qui circulent hors circuit bancaire sont faramineuses, selon la Banque d&rsquo;Alg\u00e9rie. En Alg\u00e9rie, les transactions en cash sont toujours le moyen le plus r\u00e9pondu.<\/strong><\/p>\n<p>Le rapport annuel de la Banque d&rsquo;Alg\u00e9rie pour l&rsquo;ann\u00e9e 2023, rendu public r\u00e9cemment, indique que \u00ab malgr\u00e9 une croissance moins importante que l\u2019ann\u00e9e pr\u00e9c\u00e9dente (2022, NDLR), la circulation fiduciaire hors banques a contribu\u00e9 \u00e0 hauteur de 46,7 % \u00e0 la croissance de la masse mon\u00e9taire \u00bb.<\/p>\n<p><a href=\"https:\/\/econostrum.info\/algerie\/reserves-de-change-croissance-inflation-banque-dalgerie\/\" target=\"_blank\" rel=\"noopener\">L&rsquo;argent circulant dans le circuit informel<\/a>, qui constitue un obstacle pour l&rsquo;\u00e9conomie national, reste donc \u00e0 un niveau tr\u00e8s \u00e9lev\u00e9. Le rapport retra\u00e7ant les \u00e9volutions \u00e9conomiques et mon\u00e9taires du pays en 2023 met donc en avant les manques dans la bancarisation de l&rsquo;argent qui circle dans l&rsquo;informel.<\/p>\n<p>Cependant, l&rsquo;institution financi\u00e8re indique que plusieurs chantiers sont lanc\u00e9s pour attirer ces fonds. \u00ab Plusieurs chantiers ont \u00e9t\u00e9 d\u00e9j\u00e0 lanc\u00e9s et \u00e9taient en phase de finalisation \u00e0 fin 2023 \u00bb, r\u00e9v\u00e8le la BA qui explique que les mesures prises par les pouvoirs publics visent \u00ab une meilleure inclusion financi\u00e8re par l\u2019introduction de moyens de paiement modernes \u00bb.<\/p>\n<p>L&rsquo;argent de l&rsquo;informel est \u00ab une composante significative de la masse mon\u00e9taire, avec une part de 34 % \u00bb, note encore l&rsquo;institution financi\u00e8re qui affirme que cela pose \u00ab un d\u00e9fi majeur pour l\u2019inclusion financi\u00e8re en Alg\u00e9rie \u00bb. Toutefois, selon cette institution, le secteur bancaire a enregistr\u00e9 \u00ab une \u00e9volution positive en 2023 \u00bb, en termes d\u2019indicateurs d\u2019interm\u00e9diation bancaire et de bancarisation des populations.<\/p>\n<p>Il faut dire que le paysage bancaire local a vu son r\u00e9seau direct s\u2019\u00e9tendre \u00e0 1 746 agences fin 2023, contre 1 720 fin 2022. Il est d\u00e9sormais compos\u00e9 de 7 banques publiques, 13 priv\u00e9es \u00e0 capitaux \u00e9trangers, dont une \u00e0 capitaux mixtes, 2 \u00e9tablissements financiers publics, 5 soci\u00e9t\u00e9s de leasing, dont 3 publiques, et une mutuelle d\u2019assurance agricole agr\u00e9\u00e9e pour effectuer des op\u00e9rations de banque.<\/p>\n<p>Ces chiffres \u00ab traduisent une densit\u00e9 d\u2019une agence pour 26 690 habitants \u00bb, alors que \u00ab le ratio population active\/guichets bancaires, s\u2019est l\u00e9g\u00e8rement am\u00e9lior\u00e9 en 2023, soit un guichet pour 8 141 personnes en \u00e2ge de travailler, contre 8 238 personnes pour l\u2019ann\u00e9e pr\u00e9c\u00e9dente \u00bb, indique la <a href=\"https:\/\/www.bank-of-algeria.dz\/\" target=\"_blank\" rel=\"noopener\">Banque d&rsquo;Alg\u00e9rie<\/a>. Il faut ajouter \u00e0 ces institutions financi\u00e8res un r\u00e9seau de centres de ch\u00e8ques postaux, compos\u00e9 de 4 209 agences r\u00e9parties sur l\u2019ensemble du territoire national, soit un \u00e9tablissement postal pour 3 189 personnes actives.<\/p>\n<h2>D\u00e9veloppement de moyens de payement modernes pour attirer l&rsquo;argent de l&rsquo;informel<\/h2>\n<p>Le niveau de bancarisation, en termes de nombre de comptes ouverts par les banques \u00e0 la client\u00e8le (comptes actifs en dinars et en devises) et par le centre des ch\u00e8ques postaux est en l\u00e9g\u00e8re progression en 2023 et se situe \u00e0 3,41 comptes par personne en \u00e2ge de travailler, contre 3,26 comptes en 2022 indique encore l&rsquo;institution.<\/p>\n<p>Soulignons que contrairement aux moyens de paiement classiques (ch\u00e8ques et effets de commerce), dont l\u2019utilisation semble r\u00e9gresser d\u2019ann\u00e9e en ann\u00e9e, les moyens de paiement de nature essentiellement \u00e9lectronique (virements, pr\u00e9l\u00e8vements et transactions par cartes) confortent, de mieux en mieux, leur dominance en volume, selon la BA.<\/p>\n<p>En 2023, le d\u00e9veloppement de l\u2019activit\u00e9 mon\u00e9tique, soit des moyens de paiement modernes, s\u2019est traduit par un total de 16 509 507 cartes magn\u00e9tiques mises en circulation, soit un taux d\u2019accroissement de 21,1 % et un parc mon\u00e9tique de 3847 DAB\/GAB et 53 191 terminaux de paiement \u00e9lectroniques (TPE), en hausse respectivement de 5,7 % et 15 % par rapport \u00e0 2022.<\/p>\n<p>Une moyenne de 4 292 cartes \u00e9mises par DAB\/GAB (distributeurs et guichets automatiques) et de 310 cartes \u00e9mises par TPE, a \u00e9t\u00e9 enregistr\u00e9 en 2023. Toutefois, cela reste, \u00ab insignifiant en termes de points d\u2019acceptation \u00bb, souligne la BA qui ajoute que les paiements par mobile autoris\u00e9s par la Banque d\u2019Alg\u00e9rie en intra-bancaire ont enregistr\u00e9 en 2023 \u00ab une tr\u00e8s importante volum\u00e9trie de 39 millions de transactions pour une valeur globale de 28 milliards de dinars \u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le secteur de l&rsquo;informel repr\u00e9sente une partie importante de l&rsquo;\u00e9conomie en Alg\u00e9rie. Les sommes d&rsquo;argent qui circulent hors circuit bancaire sont faramineuses, selon la Banque d&rsquo;Alg\u00e9rie. En Alg\u00e9rie, les transactions &#8230; <a title=\"L&rsquo;argent de l&rsquo;informel repr\u00e9sente 34 % de la masse mon\u00e9taire en Alg\u00e9rie : les projets lanc\u00e9s pour une meilleure inclusion financi\u00e8re\" class=\"read-more\" href=\"https:\/\/econostrum.info\/algerie\/argent-de-linformel-inclusion-financiere\/\" aria-label=\"En savoir plus sur L&rsquo;argent de l&rsquo;informel repr\u00e9sente 34 % de la masse mon\u00e9taire en Alg\u00e9rie : les projets lanc\u00e9s pour une meilleure inclusion financi\u00e8re\"> <\/a><\/p>\n","protected":false},"author":5,"featured_media":4130,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4124","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/4124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/comments?post=4124"}],"version-history":[{"count":0,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/4124\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media\/4130"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media?parent=4124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/categories?post=4124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/tags?post=4124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}