{"id":3582,"date":"2024-07-14T15:21:34","date_gmt":"2024-07-14T14:21:34","guid":{"rendered":"https:\/\/econostrum.info\/algerie\/?p=3582"},"modified":"2024-07-14T15:21:35","modified_gmt":"2024-07-14T14:21:35","slug":"investissement-algerie-lion-group","status":"publish","type":"post","link":"https:\/\/econostrum.info\/algerie\/investissement-algerie-lion-group\/","title":{"rendered":"Investissement en Alg\u00e9rie : le Malaisien \u00ab\u00a0Lion Group\u00bb affiche ses ambitions dans plusieurs secteurs"},"content":{"rendered":"<p><strong>L&rsquo;Alg\u00e9rie attire de plus en plus d&rsquo;investissements ces derniers temps apr\u00e8s des ann\u00e9es de disette. Plusieurs pays et groupes de renomm\u00e9e mondiale ont exprim\u00e9 leur volont\u00e9 de renforcer leur pr\u00e9sence dans le pays. C&rsquo;est le cas du groupe malaisien Lion Group qui envisage notamment de se lancer dans la production de l\u2019aluminium et de la sid\u00e9rurgie.<\/strong><\/p>\n<p>En effet, le groupe avait exprim\u00e9 sa volont\u00e9 d\u2019investir 8 milliards de dollars dans la production de l\u2019aluminium et dans la sid\u00e9rurgie. Lion Group ne s&rsquo;arr\u00eate cependant pas l\u00e0. Il a entam\u00e9 une s\u00e9rie de discussions avec les ministres de l\u2019Industrie et de la production pharmaceutique, celui de l\u2019\u00c9nergie et des Mines, ainsi qu&rsquo;avec le ministre des Finances.<\/p>\n<p>Avec le ministre de l&rsquo;\u00c9nergie et de mines, la d\u00e9l\u00e9gation malaisienne conduite par le PDG du groupe Lion, M. Tan Sri Datuk Seri Utama William Chang, a affich\u00e9 ses ambitions dans les domaines de l\u2019exploitation des ressources mini\u00e8res et la fabrication de panneaux solaires photovolta\u00efques.<\/p>\n<h2>L&rsquo;investissement dans l&rsquo;exploitation de ressources mini\u00e8res dans la ligne de mire de Lion Group<\/h2>\n<p>La m\u00eame d\u00e9l\u00e9gation est revenue sur les projets que le groupe envisage de lancer dans la production de l\u2019aluminium et de la sid\u00e9rurgie, avec <a href=\"https:\/\/www.mf.gov.dz\/index.php\/fr\/#:~:text=Monsieur%20Laaziz%20FAID%2C%20Ministre%20des,l&#039;Afrique%20(OSAA).\" target=\"_blank\" rel=\"noopener\">le ministre des Finances<\/a>. La partie malaisienne a indiqu\u00e9 \u00eatre \u00ab <em>rassur\u00e9e quant aux bonnes conditions d\u2019investissement offertes par l\u2019Alg\u00e9rie, \u00e0 la faveur notamment de la panoplie de r\u00e9formes entreprises par les pouvoirs publics pour am\u00e9liorer l\u2019\u00e9cosyst\u00e8me de conduite des affaires<\/em> \u00bb, selon le communiqu\u00e9 du minist\u00e8re.<\/p>\n<p>Le ministre alg\u00e9rien des Finances, Laaziz Fa\u00efd, a assur\u00e9, de son c\u00f4t\u00e9, de la disponibilit\u00e9 des pouvoirs publics alg\u00e9riens \u00e0 \u00ab <em>garantir la r\u00e9ussite et le succ\u00e8s de ce <a href=\"https:\/\/econostrum.info\/algerie\/etats-unis-doubler-investissements-algerie\/\" target=\"_blank\" rel=\"noopener\">partenariat strat\u00e9gique<\/a><\/em> \u00bb. Les deux parties s\u2019engagent \u00e0 \u00ab <em>concr\u00e9tiser les projets porteurs de croissance et de d\u00e9veloppement \u00e9conomique dans une d\u00e9marche gagnant-gagnant<\/em> \u00bb, souligne le communiqu\u00e9 du d\u00e9partement de Laazi Fa\u00efd.<\/p>\n<p>Rappelons que depuis ao\u00fbt 2023, Lion Group a entam\u00e9 des d\u00e9marches pour l\u2019entame des proc\u00e9dures d\u2019inscription du portefeuille de projets du groupe aupr\u00e8s de l\u2019Agence alg\u00e9rienne de promotion de l\u2019investissement AAPI. Un portefeuille qui comprend\u00a0 \u00ab <em>des projets d\u2019exploitation de ressources mini\u00e8res, comme l\u2019aluminium et les minerais de fer destin\u00e9s \u00e0 l\u2019exploitation industrielle, devant \u00eatre r\u00e9alis\u00e9s en deux phases<\/em> \u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Alg\u00e9rie attire de plus en plus d&rsquo;investissements ces derniers temps apr\u00e8s des ann\u00e9es de disette. Plusieurs pays et groupes de renomm\u00e9e mondiale ont exprim\u00e9 leur volont\u00e9 de renforcer leur pr\u00e9sence &#8230; <a title=\"Investissement en Alg\u00e9rie : le Malaisien \u00ab\u00a0Lion Group\u00bb affiche ses ambitions dans plusieurs secteurs\" class=\"read-more\" href=\"https:\/\/econostrum.info\/algerie\/investissement-algerie-lion-group\/\" aria-label=\"En savoir plus sur Investissement en Alg\u00e9rie : le Malaisien \u00ab\u00a0Lion Group\u00bb affiche ses ambitions dans plusieurs secteurs\"> <\/a><\/p>\n","protected":false},"author":5,"featured_media":3586,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,1],"tags":[],"class_list":["post-3582","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-investissements","category-economie","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/3582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/comments?post=3582"}],"version-history":[{"count":0,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/3582\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media\/3586"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media?parent=3582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/categories?post=3582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/tags?post=3582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}