{"id":3534,"date":"2024-07-10T16:05:57","date_gmt":"2024-07-10T15:05:57","guid":{"rendered":"https:\/\/econostrum.info\/algerie\/?p=3534"},"modified":"2024-07-10T16:05:57","modified_gmt":"2024-07-10T15:05:57","slug":"40-pib-economie-parallele-defi-algerie","status":"publish","type":"post","link":"https:\/\/econostrum.info\/algerie\/40-pib-economie-parallele-defi-algerie\/","title":{"rendered":"Repr\u00e9sentant 40 % du PIB, selon Laaziz Faid, l&rsquo;int\u00e9gration de l&rsquo;\u00e9conomie parall\u00e8le repr\u00e9sente un d\u00e9fi pour l&rsquo;Alg\u00e9rie"},"content":{"rendered":"<p><strong>Le secteur de l&rsquo;\u00e9conomie parall\u00e8le, appel\u00e9 \u00e9galement secteur de l&rsquo;informel, repr\u00e9sente une bonne partie de l&rsquo;\u00e9conomie en Alg\u00e9rie. Les sommes d&rsquo;argent qui circulent hors circuit bancaire sont faramineuses, ne cesse d&rsquo;alerter la Banque d&rsquo;Alg\u00e9rie. Le ministre des Finances, Laaziz Faid, confirme ce constat et consid\u00e8re que l&rsquo;Alg\u00e9rie fait face au d\u00e9fi de capter l&rsquo;argent du secteur parall\u00e8le.<\/strong><\/p>\n<p>Le ministre des Finances s&rsquo;est exprim\u00e9 lors de l\u2019ouverture d\u2019une journ\u00e9e d\u2019information organis\u00e9e le 9 juillet par l\u2019Inspection G\u00e9n\u00e9rale des Finances (IGF). Ayant pour th\u00e8me \u00ab l&rsquo;\u00e9valuation des politiques publiques \u00e0 la lumi\u00e8re de la loi organique relative aux lois de finances \u00bb, cette journ\u00e9e a \u00e9t\u00e9 une occasion pour Laaziz Faid de mettre en avant la n\u00e9cessit\u00e9 de l\u2019adaptation du contr\u00f4le financier conventionnel exerc\u00e9 par la Cour des comptes, l\u2019Inspection G\u00e9n\u00e9rale des Finances (IGF) et les contr\u00f4leurs de gestion, au contexte actuel de la gestion budg\u00e9taire.<\/p>\n<p>Le ministre a \u00e9galement affirm\u00e9 que les d\u00e9fis futurs du pays concernaient l\u2019<a href=\"https:\/\/econostrum.info\/algerie\/argent-informel-banque-dalgerienancieres\/\" target=\"_blank\" rel=\"noopener\">int\u00e9gration de l\u2019\u00e9conomie parall\u00e8le<\/a> qui repr\u00e9sente \u00ab <em>40% du PIB<\/em> \u00bb, ainsi que l\u2019orientation vers une subvention cibl\u00e9e afin de garantir une r\u00e9partition \u00e9quitable de la richesse. En gagnant ces d\u00e9fis, l\u2019Alg\u00e9rie \u00ab <em>sera capable de figurer, dans trois ans, parmi les pays \u00e9mergents<\/em> \u00bb, affirme Laaziz Faid.<\/p>\n<h2>Le contr\u00f4le financier conventionnel doit \u00e9voluer<\/h2>\n<p>Par ailleurs, <a href=\"https:\/\/www.mf.gov.dz\/index.php\/fr\/\" target=\"_blank\" rel=\"noopener\">le ministre a indiqu\u00e9<\/a> que \u00ab <em>le contr\u00f4le financier conventionnel exerc\u00e9 actuellement par la Cour des comptes, l\u2019IGF et le contr\u00f4leur de gestion (anciennement le contr\u00f4leur financier) doit \u00e9voluer et s\u2019adapter au contexte actuel de la gestion budg\u00e9taire<\/em> \u00bb. Pour ce responsable, le contr\u00f4le de conformit\u00e9 aux lois ne devrait pas rester la norme, mais devrait plut\u00f4t \u00eatre int\u00e9gr\u00e9, progressivement, dans le cadre d\u2019une approche plus large du contr\u00f4le strat\u00e9gique, qu\u2019on appelle \u00ab l&rsquo;\u00e9valuation \u00bb.<\/p>\n<p>L\u2019\u00e9valuation de la gestion des finances publiques reposait sur la r\u00e9alisation d\u2019objectifs pr\u00e9alablement d\u00e9finis qui, en effet, ont \u00e9t\u00e9 fix\u00e9s sur la base de crit\u00e8res pr\u00e9cis et mesurables, souligne encore le ministre. Ce dernier rappelle que l\u2019\u00e9valuation constituait un outil de gouvernance efficace permettant d\u2019am\u00e9liorer la performance du secteur public \u00e0 travers la rationalisation des d\u00e9penses publiques.<\/p>\n<p>Pour que cette \u00e9valuation soit efficace, Laaziz Faid estime qu&rsquo;un dialogue interactif, associant les partenaires et les acteurs, est important. Ce dialogue est m\u00eame \u00ab <em>une condition fondamentale pour l\u2019application des recommandations de l\u2019\u00e9valuation et ses r\u00e9sultats<\/em> \u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le secteur de l&rsquo;\u00e9conomie parall\u00e8le, appel\u00e9 \u00e9galement secteur de l&rsquo;informel, repr\u00e9sente une bonne partie de l&rsquo;\u00e9conomie en Alg\u00e9rie. Les sommes d&rsquo;argent qui circulent hors circuit bancaire sont faramineuses, ne cesse &#8230; <a title=\"Repr\u00e9sentant 40 % du PIB, selon Laaziz Faid, l&rsquo;int\u00e9gration de l&rsquo;\u00e9conomie parall\u00e8le repr\u00e9sente un d\u00e9fi pour l&rsquo;Alg\u00e9rie\" class=\"read-more\" href=\"https:\/\/econostrum.info\/algerie\/40-pib-economie-parallele-defi-algerie\/\" aria-label=\"En savoir plus sur Repr\u00e9sentant 40 % du PIB, selon Laaziz Faid, l&rsquo;int\u00e9gration de l&rsquo;\u00e9conomie parall\u00e8le repr\u00e9sente un d\u00e9fi pour l&rsquo;Alg\u00e9rie\"> <\/a><\/p>\n","protected":false},"author":5,"featured_media":2556,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3534","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/3534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/comments?post=3534"}],"version-history":[{"count":0,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/3534\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media\/2556"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media?parent=3534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/categories?post=3534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/tags?post=3534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}