{"id":3404,"date":"2024-07-03T16:04:32","date_gmt":"2024-07-03T15:04:32","guid":{"rendered":"https:\/\/econostrum.info\/algerie\/?p=3404"},"modified":"2024-07-03T16:04:32","modified_gmt":"2024-07-03T15:04:32","slug":"vice-president-banque-mondiale-algerie","status":"publish","type":"post","link":"https:\/\/econostrum.info\/algerie\/vice-president-banque-mondiale-algerie\/","title":{"rendered":"Re\u00e7u par des ministres, le vice-pr\u00e9sident de la Banque mondiale qualifie l&rsquo;Alg\u00e9rie de \u00ab\u00a0mod\u00e8le de r\u00e9ussite\u00a0\u00bb"},"content":{"rendered":"<p><strong>L&rsquo;\u00e9conomie alg\u00e9rienne progresse dans plusieurs secteurs. L&rsquo;Alg\u00e9rie, class\u00e9e jusqu&rsquo;ici dans le palier de \u00ab pays \u00e0 revenu interm\u00e9diaire de la tranche inf\u00e9rieure \u00bb, passera d\u00e9sormais \u00e0 un nouveau palier de \u00ab pays \u00e0 revenu interm\u00e9diaire de la tranche sup\u00e9rieure \u00bb, selon la mise \u00e0 jour de la Banque mondiale publi\u00e9e r\u00e9cemment. Ce constat a \u00e9t\u00e9 confirm\u00e9 par le vice-pr\u00e9sident de la Banque Mondiale (BM) en charge de la r\u00e9gion Moyen-Orient et Afrique du Nord (MENA), Osmane Dione, lors de sa rencontre avec le ministre alg\u00e9rien des Finances, Laaziz Faid.<\/strong><\/p>\n<p>En effet, le haut responsable de la BM a visit\u00e9 l&rsquo;Alg\u00e9rie et a rencontr\u00e9 plusieurs hauts responsables dont le ministre de l&rsquo;\u00c9nergie et celui des finances. Lors de sa rencontre avec Laaziz Faid, le haut responsable de l&rsquo;institution financi\u00e8re mondiale a tenu \u00e0 saluer \u00ab <em>les performances enregistr\u00e9es et reconnues par la Communaut\u00e9 internationale de d\u00e9veloppement<\/em> \u00bb.<\/p>\n<h2>L&rsquo;Alg\u00e9rie, un \u00ab mod\u00e8le de r\u00e9ussite qui m\u00e9rite d\u2019\u00eatre partag\u00e9 avec les autres pays en Afrique&#8230; \u00bb<\/h2>\n<p>Selon Osmane Dione, ces performances ont permis r\u00e9cemment <a href=\"https:\/\/econostrum.info\/algerie\/rnb-habitant-algerie-palier-superieur\/\" target=\"_blank\" rel=\"noopener\">un reclassement de la position de l\u2019Alg\u00e9rie<\/a>. Les avanc\u00e9es r\u00e9alis\u00e9es par le pays sont un \u00ab <em>mod\u00e8le de r\u00e9ussite qui m\u00e9rite d\u2019\u00eatre partag\u00e9 avec les autres pays en Afrique et dans la r\u00e9gion MENA <\/em>\u00bb, a ajout\u00e9 le vice-pr\u00e9sident de la BM, selon le communiqu\u00e9 du minist\u00e8re des Finances.<\/p>\n<p>\u00ab <em>Gr\u00e2ce \u00e0 sa stabilit\u00e9 g\u00e9opolitique, sa dynamique \u00e9conomique, sa ressource humaine et sa jeunesse, ainsi qu\u2019\u00e0 sa position g\u00e9ographique, sa connectivit\u00e9 r\u00e9gionale, son potentiel en tant que hub logistique et son acc\u00e8s aux march\u00e9s europ\u00e9ens, africains et arabes<\/em> \u00bb, l&rsquo;Alg\u00e9rie peut jouer un r\u00f4le moteur sur le plan \u00e9conomique de la r\u00e9gion MENA, ajoute Osmane Dione. Par ailleurs, ce responsable s&rsquo;est exprim\u00e9 sur la situation de la coop\u00e9ration de son institution avec l&rsquo;Alg\u00e9rie. Il a affirm\u00e9 que la <a href=\"https:\/\/www.banquemondiale.org\/fr\/home\" target=\"_blank\" rel=\"noopener\">BM<\/a> est dispos\u00e9e \u00e0 donner un nouveau souffle aux relations de coop\u00e9ration la liant \u00e0 l\u2019Alg\u00e9rie.<\/p>\n<p>Pour sa part, le ministre des Finances a d&#8217;embl\u00e9e pr\u00e9sent\u00e9 la trajectoire emprunt\u00e9e par l\u2019Alg\u00e9rie pour un d\u00e9veloppement durable et inclusif. Il a indiqu\u00e9 que la politique \u00e9conomique du pays est guid\u00e9e par des objectifs r\u00e9alistes inscrits dans le plan d\u2019action du gouvernement et d\u00e9coulant des engagements pr\u00e9sidentiels. Cette trajectoire \u00ab <em>a men\u00e9 l\u2019Alg\u00e9rie \u00e0 engager un programme ambitieux de r\u00e9formes structurelles dans des domaines cl\u00e9s, et \u00e0 revoir certains textes fondamentaux de son arsenal juridique r\u00e9gissant l\u2019environnement des affaires<\/em> \u00bb, a indiqu\u00e9 Laaziz Faid.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00e9conomie alg\u00e9rienne progresse dans plusieurs secteurs. L&rsquo;Alg\u00e9rie, class\u00e9e jusqu&rsquo;ici dans le palier de \u00ab pays \u00e0 revenu interm\u00e9diaire de la tranche inf\u00e9rieure \u00bb, passera d\u00e9sormais \u00e0 un nouveau palier de &#8230; <a title=\"Re\u00e7u par des ministres, le vice-pr\u00e9sident de la Banque mondiale qualifie l&rsquo;Alg\u00e9rie de \u00ab\u00a0mod\u00e8le de r\u00e9ussite\u00a0\u00bb\" class=\"read-more\" href=\"https:\/\/econostrum.info\/algerie\/vice-president-banque-mondiale-algerie\/\" aria-label=\"En savoir plus sur Re\u00e7u par des ministres, le vice-pr\u00e9sident de la Banque mondiale qualifie l&rsquo;Alg\u00e9rie de \u00ab\u00a0mod\u00e8le de r\u00e9ussite\u00a0\u00bb\"> <\/a><\/p>\n","protected":false},"author":5,"featured_media":3409,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/3404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/comments?post=3404"}],"version-history":[{"count":0,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/3404\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media\/3409"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media?parent=3404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/categories?post=3404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/tags?post=3404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}