{"id":3207,"date":"2024-06-23T16:09:48","date_gmt":"2024-06-23T15:09:48","guid":{"rendered":"https:\/\/econostrum.info\/algerie\/?p=3207"},"modified":"2024-06-23T16:09:48","modified_gmt":"2024-06-23T15:09:48","slug":"gaz-torche-algerie-reductions-importantes","status":"publish","type":"post","link":"https:\/\/econostrum.info\/algerie\/gaz-torche-algerie-reductions-importantes\/","title":{"rendered":"Gaz torch\u00e9 : l&rsquo;Alg\u00e9rie a r\u00e9alis\u00e9 des r\u00e9ductions importantes"},"content":{"rendered":"<p><strong>Le gaz torch\u00e9 cause une \u00e9mission de gaz \u00e0 effet de serre (dioxyde de carbone et m\u00e9thane) consid\u00e9rable, contribuant au r\u00e9chauffement climatique. Les pays producteurs de gaz et de p\u00e9trole s&#8217;emploient ainsi \u00e0 r\u00e9duire le torchage du gaz pour r\u00e9duire la pollution atmosph\u00e9rique. L&rsquo;Alg\u00e9rie, qui fait partie des neuf principaux pays responsables du torchage de gaz, r\u00e9alise une grande am\u00e9lioration en 2024, selon un rapport de Global Gas Flaring Tracker de la Banque mondiale.<\/strong><\/p>\n<p>En effet, ce rapport souligne des am\u00e9liorations soutenues en \u00ab<em> Alg\u00e9rie et au Venezuela (-4 % et 3 % d\u2019intensit\u00e9)<\/em> \u00bb. La quantit\u00e9 de gaz torch\u00e9 en 2023 dans le monde a atteint un volume global de 148 milliards de m\u00e8tres cubes. Cette quantit\u00e9 marque une hausse importante de 9 milliards de m\u00e8tres cubes (+7 %), soit le niveau le plus \u00e9lev\u00e9 depuis 2019, souligne Global Gas Flaring Tracker.<\/p>\n<p>Responsable du rejet de 381 millions de tonnes d\u2019\u00e9quivalent dioxyde de carbone CO\u2082e, dont une importante quantit\u00e9 de m\u00e9thane, soit le volume que produit l\u2019ajout de cinq millions de voitures sur les routes, le torchage de gaz continue d&rsquo;impacter le climat, indique le rapport. La F\u00e9d\u00e9ration de Russie, les \u00c9tats-Unis, la R\u00e9publique islamique d\u2019Iran, l\u2019Irak, le Venezuela, l\u2019Alg\u00e9rie, la Libye, le Nigeria et le Mexique sont responsables de 75 % du volume de gaz br\u00fbl\u00e9 \u00e0 la torche dans le monde, rappelle <a href=\"https:\/\/www.worldbank.org\/en\/programs\/gasflaringreduction\/global-flaring-data\" target=\"_blank\" rel=\"noopener\">Global Gas Flaring Tracker<\/a>.<\/p>\n<h2>L&rsquo;Alg\u00e9rie a r\u00e9duit les quantit\u00e9s de gaz torch\u00e9<\/h2>\n<p>Toutefois, ce rapport souligne que la r\u00e9duction la plus importante du torchage a \u00e9t\u00e9 observ\u00e9e, l\u2019ann\u00e9e derni\u00e8re, en Alg\u00e9rie. \u00ab <em>Les volumes br\u00fbl\u00e9s ont diminu\u00e9 de 0,4 milliard de m\u00e8tres cubes, soit 5 %<\/em> \u00bb, indique les r\u00e9dacteurs dudit rapport.<\/p>\n<p>Cet outil de surveillance des gaz torch\u00e9s fait remarquer que \u00ab <em>depuis 2020, la compagnie p\u00e9troli\u00e8re Sonatrach a mis en \u0153uvre plusieurs projets de r\u00e9cup\u00e9ration du gaz torch\u00e9 \u00e0 Hassi Messaoud, <a href=\"https:\/\/econostrum.info\/algerie\/energie-sonatrach-accord-totalenergies\/\" target=\"_blank\" rel=\"noopener\">le plus grand champ p\u00e9trolie<\/a>r du pays<\/em> \u00bb. Il ajoute qu&rsquo;en \u00ab <em>2023, la compagnie s\u2019est engag\u00e9e \u00e0 r\u00e9aliser des projets dans d\u2019autres champs, notamment dans ceux de Tiguentourine, d\u2019Ohanet et de Tin-Fouy\u00e9-Tabenkort, qui devraient permettre de r\u00e9duire davantage les volumes de torchage en Alg\u00e9rie<\/em> \u00bb.<\/p>\n<p>\u00ab<em> Apr\u00e8s les succ\u00e8s consid\u00e9rables enregistr\u00e9s, l\u2019an dernier, dans des pays, tels que les \u00c9tats-Unis et l\u2019Angola, cette ann\u00e9e, nous constatons des am\u00e9liorations soutenues en Alg\u00e9rie et au Venezuela (-4 % et 3 % d\u2019intensit\u00e9)<\/em> \u00bb, souligne encore Global Gas Flaring Tracker.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le gaz torch\u00e9 cause une \u00e9mission de gaz \u00e0 effet de serre (dioxyde de carbone et m\u00e9thane) consid\u00e9rable, contribuant au r\u00e9chauffement climatique. Les pays producteurs de gaz et de p\u00e9trole &#8230; <a title=\"Gaz torch\u00e9 : l&rsquo;Alg\u00e9rie a r\u00e9alis\u00e9 des r\u00e9ductions importantes\" class=\"read-more\" href=\"https:\/\/econostrum.info\/algerie\/gaz-torche-algerie-reductions-importantes\/\" aria-label=\"En savoir plus sur Gaz torch\u00e9 : l&rsquo;Alg\u00e9rie a r\u00e9alis\u00e9 des r\u00e9ductions importantes\"> <\/a><\/p>\n","protected":false},"author":5,"featured_media":3209,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-3207","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energie","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/3207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/comments?post=3207"}],"version-history":[{"count":0,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/3207\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media\/3209"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media?parent=3207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/categories?post=3207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/tags?post=3207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}