{"id":2919,"date":"2024-06-06T11:26:43","date_gmt":"2024-06-06T10:26:43","guid":{"rendered":"https:\/\/econostrum.info\/algerie\/?p=2919"},"modified":"2024-06-06T11:26:43","modified_gmt":"2024-06-06T10:26:43","slug":"moutons-roumanie-aid-el-kebir-algerie","status":"publish","type":"post","link":"https:\/\/econostrum.info\/algerie\/moutons-roumanie-aid-el-kebir-algerie\/","title":{"rendered":"Des moutons de Roumanie vendus pour l&rsquo;A\u00efd el-K\u00e9bir en Alg\u00e9rie ?"},"content":{"rendered":"<p><strong>Cette ann\u00e9e, l&rsquo;A\u00efd al-Adha, appel\u00e9e \u00e9galement A\u00efd el-Kebir, sera f\u00eat\u00e9e le 16 juin. La c\u00e9l\u00e9bration de cette f\u00eate, la plus importante du calendrier musulman, se fait notamment par le sacrifice d&rsquo;un mouton. Toutefois, les prix du b\u00e9tail ont flamb\u00e9 dans le pays. Les Alg\u00e9riens dans l&rsquo;incapacit\u00e9 de se permettre une telle d\u00e9pense sont nombreux, d&rsquo;o\u00f9 <\/strong><strong>la question sur une intervention de l&rsquo;\u00c9tat en important des moutons de la Roumanie. Des ovins cens\u00e9s co\u00fbter moins cher sur les march\u00e9s locaux.<\/strong><\/p>\n<p>\u00c0 quelques jours de l&rsquo;A\u00efd, les prix des moutons ont atteint des niveaux tr\u00e8s \u00e9lev\u00e9s en Alg\u00e9rie. Pour peser sur le march\u00e9, ils sont nombreux \u00e0 pr\u00e9coniser <a href=\"https:\/\/econostrum.info\/algerie\/importation-de-moutons-roumanie-alviar\/\" target=\"_blank\" rel=\"noopener\">l&rsquo;importation de moutons<\/a> \u00e0 partir de la Roumanie. Cette proposition a \u00e9t\u00e9 tranch\u00e9e par le ministre de l\u2019Agriculture et du D\u00e9veloppement rural, Youssef Cherfa, dans une d\u00e9claration \u00e0 la presse, le 4 juin.<\/p>\n<p>Ce haut responsable du <a href=\"https:\/\/fr.madr.gov.dz\/?playlist=4a0503b&amp;video=9ed131c\" target=\"_blank\" rel=\"noopener\">secteur de l&rsquo;agriculture\u00a0<\/a>a indiqu\u00e9 qu\u2019il n&rsquo;y avait aucun processus d\u2019importation de b\u00e9tail roumain en guise de sacrifice pour la f\u00eate de l\u2019A\u00efd el-K\u00e9bir cette ann\u00e9e. Youssef Cherfa, qui s&rsquo;est exprim\u00e9 en marge de sa visite dans la wilaya de Bouira, a affirm\u00e9 que \u00ab <em>le produit national, en mati\u00e8re d\u2019\u00e9levage de b\u00e9tail, couvre suffisamment la demande du pays, malgr\u00e9 la hausse des prix cette ann\u00e9e<\/em> \u00bb.<\/p>\n<p>Les Alg\u00e9riens devront donc se contenter des moutons propos\u00e9s par les producteurs locaux, sachant que les prix ont flamb\u00e9 ces derniers jours. Le mouton co\u00fbte d\u00e9sormais jusqu\u2019\u00e0 cinq fois le salaire de base en Alg\u00e9rie. Pour ceux qui sont dans l&rsquo;incapacit\u00e9 d&rsquo;acheter local, l&rsquo;espoir d&rsquo;acheter un mouton roumain \u00e0 35 000 DA vient donc de s&rsquo;\u00e9vaporer.<\/p>\n<h2>L&rsquo;Alviar met en vent des moutons pour l&rsquo;A\u00efd el-K\u00e9bir<\/h2>\n<p>Il faut souligner que l\u2019Alg\u00e9rienne des viandes rouges (Alviar) va proc\u00e9der, \u00e0 partir du 8 juin, \u00e0 la vente de moutons pour l\u2019A\u00efd El-Adha au niveau de son point de vente \u00e0 Birtouta (Alger). Ces ovins seront propos\u00e9s entre 59 000 DA et 90 000 DA, a indiqu\u00e9 son directeur g\u00e9n\u00e9ral, Ziani Ali.<\/p>\n<p>\u00ab <em>L\u2019op\u00e9ration de vente sera lanc\u00e9e au niveau des d\u00e9p\u00f4ts de la soci\u00e9t\u00e9 sise \u00e0 Birtouta \u00e0 partir de samedi 8 juin et se poursuivra jusqu\u2019\u00e0 la veille de l\u2019Aid El Adha, \u00e0 des prix fix\u00e9s \u00e0 59.000 DA, 79.000 DA et 90.000 DA selon le poids du mouton<\/em> \u00bb, affirme le m\u00eame responsable.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cette ann\u00e9e, l&rsquo;A\u00efd al-Adha, appel\u00e9e \u00e9galement A\u00efd el-Kebir, sera f\u00eat\u00e9e le 16 juin. La c\u00e9l\u00e9bration de cette f\u00eate, la plus importante du calendrier musulman, se fait notamment par le sacrifice &#8230; <a title=\"Des moutons de Roumanie vendus pour l&rsquo;A\u00efd el-K\u00e9bir en Alg\u00e9rie ?\" class=\"read-more\" href=\"https:\/\/econostrum.info\/algerie\/moutons-roumanie-aid-el-kebir-algerie\/\" aria-label=\"En savoir plus sur Des moutons de Roumanie vendus pour l&rsquo;A\u00efd el-K\u00e9bir en Alg\u00e9rie ?\"> <\/a><\/p>\n","protected":false},"author":5,"featured_media":2928,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2919","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/2919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/comments?post=2919"}],"version-history":[{"count":0,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/2919\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media\/2928"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media?parent=2919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/categories?post=2919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/tags?post=2919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}