{"id":2908,"date":"2024-06-05T16:49:45","date_gmt":"2024-06-05T15:49:45","guid":{"rendered":"https:\/\/econostrum.info\/algerie\/?p=2908"},"modified":"2024-06-05T16:49:45","modified_gmt":"2024-06-05T15:49:45","slug":"hydrogene-vert-algerie-chine-course","status":"publish","type":"post","link":"https:\/\/econostrum.info\/algerie\/hydrogene-vert-algerie-chine-course\/","title":{"rendered":"Hydrog\u00e8ne vert en Alg\u00e9rie : apr\u00e8s l\u2019Allemagne, la Belgique, l&rsquo;Italie\u2026, la Chine entre en course"},"content":{"rendered":"<p><strong>L&rsquo;Alg\u00e9rie nourrit de grandes ambitions concernant l&rsquo;hydrog\u00e8ne vert. Elle compte devenir un fournisseur incontournable de l&rsquo;Europe en cette \u00e9nergie. Le pays a, en effet, comme objectif de fournir au Vieux continent 10 % de ses besoins en hydrog\u00e8ne vert d&rsquo;ici \u00e0 2040. Pour y arriver, il multiplie les partenariats avec des puissances europ\u00e9ennes.<\/strong><\/p>\n<p>Ainsi, l\u2019Alg\u00e9rie, dont les r\u00e9serves de gaz naturel figurent parmi les plus importantes de la plan\u00e8te, compte \u00e9galement exploiter l&rsquo;hydrog\u00e8ne vert. Le plan alg\u00e9rien se d\u00e9roule en trois \u00e9tapes. Le d\u00e9marrage via des projets pilotes (2023 \u00e0 2030), l&rsquo;expansion et la cr\u00e9ation de march\u00e9s (2030 \u00e0 2040) et l&rsquo;industrialisation et la comp\u00e9titivit\u00e9 du march\u00e9 (2040 \u00e0 2050).<\/p>\n<p>L\u2019Alg\u00e9rie pr\u00e9voit de produire et d&rsquo;exporter 30 \u00e0 40 TWh d&rsquo;hydrog\u00e8ne gazeux et liquide, avec un mix \u00e0 la fois compos\u00e9 d\u2019hydrog\u00e8ne bleu, produit \u00e0 partir de gaz, et d\u2019hydrog\u00e8ne vert, fabriqu\u00e9 par \u00e9lectrolyse gr\u00e2ce aux importantes ressources solaires du pays \u00e0 l&rsquo;horizon 2040.<\/p>\n<h2>Apr\u00e8s les pays occidentaux, les chinois veulent leur part du march\u00e9 alg\u00e9rien de l&rsquo;hydrog\u00e8ne vert<\/h2>\n<p>Plusieurs pays ont exprim\u00e9 leur volont\u00e9 de b\u00e9n\u00e9ficier de cette \u00e9nergie et d&rsquo;investir dans ce domaine. L&rsquo;Italie, l&rsquo;Allemagne et la Belgique <a href=\"https:\/\/econostrum.info\/algerie\/belgique-sinteresse-hydrogene-vert-algerie\/\" target=\"_blank\" rel=\"noopener\">ont d\u00e9j\u00e0 sign\u00e9 des accords avec l&rsquo;Alg\u00e9rie<\/a>. La Chine, d\u00e9j\u00e0 pr\u00e9sente dans divers secteurs au pays, est entr\u00e9e en course.<\/p>\n<p>En effet, le groupe China Power Engineering Consulting Group (CPECC), leader dans le domaine des \u00e9nergies nouvelles, compte investir en Alg\u00e9rie. Une d\u00e9l\u00e9gation conduite par le directeur g\u00e9n\u00e9ral du groupe, Chen Xiang Dong, a rencontr\u00e9 Omar Rekkache, directeur g\u00e9n\u00e9ral de l\u2019agence alg\u00e9rienne pour la promotion de l\u2019investissement (<a href=\"https:\/\/aapi.dz\/#:~:text=Est%20un%20%C3%A9tablissement%20public%20%C3%A0,de%20leurs%20projets%20d&#039;investissement.\" target=\"_blank\" rel=\"noopener\">Aapi<\/a>).<\/p>\n<p>Le groupe CPECC a affich\u00e9 \u00ab <em>sa volont\u00e9 d\u2019investir en Alg\u00e9rie dans la production de l\u2019hydrog\u00e8ne vert, ainsi que dans les champs de dessalement de l\u2019eau de mer<\/em> \u00bb, indique le communiqu\u00e9 de la partie alg\u00e9rienne. La Chine veut ainsi se faire une place dans ce domaine aux c\u00f4t\u00e9s des Italiens, des Allemands, des Fran\u00e7ais, des Danois et des Am\u00e9ricains qui ont affich\u00e9 leur int\u00e9r\u00eat pour l\u2019investissement en Alg\u00e9rie dans ce secteur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Alg\u00e9rie nourrit de grandes ambitions concernant l&rsquo;hydrog\u00e8ne vert. Elle compte devenir un fournisseur incontournable de l&rsquo;Europe en cette \u00e9nergie. Le pays a, en effet, comme objectif de fournir au Vieux &#8230; <a title=\"Hydrog\u00e8ne vert en Alg\u00e9rie : apr\u00e8s l\u2019Allemagne, la Belgique, l&rsquo;Italie\u2026, la Chine entre en course\" class=\"read-more\" href=\"https:\/\/econostrum.info\/algerie\/hydrogene-vert-algerie-chine-course\/\" aria-label=\"En savoir plus sur Hydrog\u00e8ne vert en Alg\u00e9rie : apr\u00e8s l\u2019Allemagne, la Belgique, l&rsquo;Italie\u2026, la Chine entre en course\"> <\/a><\/p>\n","protected":false},"author":5,"featured_media":2911,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-2908","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energie","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/2908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/comments?post=2908"}],"version-history":[{"count":0,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/2908\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media\/2911"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media?parent=2908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/categories?post=2908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/tags?post=2908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}