{"id":2319,"date":"2024-05-09T14:00:45","date_gmt":"2024-05-09T13:00:45","guid":{"rendered":"https:\/\/econostrum.info\/algerie\/?p=2319"},"modified":"2024-05-09T12:47:43","modified_gmt":"2024-05-09T11:47:43","slug":"vulkan-installe-usine-africaine-algerie","status":"publish","type":"post","link":"https:\/\/econostrum.info\/algerie\/vulkan-installe-usine-africaine-algerie\/","title":{"rendered":"Le groupe allemand Vulkan installe sa premi\u00e8re usine africaine en Alg\u00e9rie"},"content":{"rendered":"<p><strong>Pour faire face \u00e0 la concurrence, plusieurs entreprises allemandes ont d\u00e9cid\u00e9 de d\u00e9localiser leur production \u00e0 l&rsquo;\u00e9tranger. En cause, les co\u00fbts de production dans ce pays qui sont parmi les plus \u00e9lev\u00e9s en Europe. Cela repr\u00e9sente une opportunit\u00e9 pour d&rsquo;autres pays, tels que l&rsquo;Alg\u00e9rie, qui avait exprim\u00e9, depuis plusieurs semaines, son souhait d&rsquo;accueillir les entreprises allemandes.<\/strong><\/p>\n<p>Il faut dire que la volont\u00e9 d&rsquo;aller dans cette direction pour les entreprises allemande s&rsquo;est exprim\u00e9e bien avant que la crise qui secoue le pays ne s&rsquo;installe plus durement. Une \u00e9tude de la F\u00e9d\u00e9ration des industries allemandes (Bundesverband der Deutschen Industrie, BDI) avait r\u00e9v\u00e9l\u00e9 que plusieurs entreprises avaient entam\u00e9 le processus de d\u00e9localisation des emplois et de la production \u00e0 l\u2019\u00e9tranger, dans une conjoncture o\u00f9 les inqui\u00e9tudes concernant l\u2019\u00e9conomie allemande ne cessaient de cro\u00eetre.<\/p>\n<p>Profitant de cette opportunit\u00e9, l&rsquo;Alg\u00e9rie avait exprim\u00e9 son souhait d&rsquo;accueillir ces entreprises. \u00ab <em>L\u2019Alg\u00e9rie est dispos\u00e9e \u00e0 faciliter la mise en place de projets de colocalisation dans l\u2019ensemble des secteurs d\u2019activit\u00e9 en faveur des entreprises allemandes<\/em> \u00bb. C&rsquo;est ce qu&rsquo;avait d\u00e9clar\u00e9, en mars dernier, <a href=\"https:\/\/www.industrie.gov.dz\/fr\/ministre\/\" target=\"_blank\" rel=\"noopener\">le ministre de l\u2019Industrie et de la production pharmaceutique<\/a>, Ali Aoun, \u00e0 l\u2019adresse des acteurs \u00e9conomiques allemands, \u00e0 l\u2019occasion de sa participation aux travaux du forum annuel de l\u2019Association f\u00e9d\u00e9rale allemande des petites et moyennes entreprises (BVMW) \u00e0 Berlin.<\/p>\n<h2>Vulkan s\u00e9duit par les opportunit\u00e9s offertes par l&rsquo;Alg\u00e9rie<\/h2>\n<p>La strat\u00e9gie de l&rsquo;Alg\u00e9rie commence donc \u00e0 apporter ses fruits. Le groupe allemand Vulkan a d\u00e9cid\u00e9 d&rsquo;installer sa premi\u00e8re usine africaine en Alg\u00e9rie. Pr\u00e9sente il y a quelques mois au Salon international d\u2019Alger en tant qu\u2019exposant dans le secteur de l\u2019\u00e9nergie, des mines et des pi\u00e8ces m\u00e9caniques pour la construction navale, l&rsquo;entreprise allemande a \u00e9t\u00e9 s\u00e9duite par les incitations offertes par l&rsquo;Alg\u00e9rie.<\/p>\n<p>C&rsquo;est ainsi que <a href=\"https:\/\/econostrum.info\/algerie\/industrie-allemagne-delocaliser-algerie\/\" target=\"_blank\" rel=\"noopener\">l&rsquo;entreprise a d\u00e9cid\u00e9 de s&rsquo;installer en Alg\u00e9rie<\/a> en optant pour un partenariat avec la partie alg\u00e9rienne. Ainsi, la soci\u00e9t\u00e9 allemande a d\u00e9voil\u00e9 son projet de construction de sa premi\u00e8re filiale sur le sol africain, qui sera \u00e9tabli en Alg\u00e9rie, selon le communiqu\u00e9 de l&rsquo;entreprise.<\/p>\n<p>Cette entreprise est la quatri\u00e8me \u00e0 l\u2019\u00e9chelle mondiale et la premi\u00e8re en Afrique. \u00ab <em>Nous avons choisi l\u2019Alg\u00e9rie pour \u00e9tablir un partenariat en raison de sa fiabilit\u00e9. Nous suivons de pr\u00e8s les progr\u00e8s r\u00e9alis\u00e9s dans le domaine de l\u2019investissement et l\u2019am\u00e9lioration des infrastructures dans votre pays<\/em> \u00bb, a d\u00e9clar\u00e9 le PDG de Vulkan en r\u00e9ponse aux questions de journalistes de la t\u00e9l\u00e9vision publique.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour faire face \u00e0 la concurrence, plusieurs entreprises allemandes ont d\u00e9cid\u00e9 de d\u00e9localiser leur production \u00e0 l&rsquo;\u00e9tranger. En cause, les co\u00fbts de production dans ce pays qui sont parmi les &#8230; <a title=\"Le groupe allemand Vulkan installe sa premi\u00e8re usine africaine en Alg\u00e9rie\" class=\"read-more\" href=\"https:\/\/econostrum.info\/algerie\/vulkan-installe-usine-africaine-algerie\/\" aria-label=\"En savoir plus sur Le groupe allemand Vulkan installe sa premi\u00e8re usine africaine en Alg\u00e9rie\"> <\/a><\/p>\n","protected":false},"author":5,"featured_media":2321,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/2319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/comments?post=2319"}],"version-history":[{"count":0,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/2319\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media\/2321"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media?parent=2319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/categories?post=2319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/tags?post=2319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}