{"id":2276,"date":"2024-05-07T14:39:56","date_gmt":"2024-05-07T13:39:56","guid":{"rendered":"https:\/\/econostrum.info\/algerie\/?p=2276"},"modified":"2024-05-07T14:39:56","modified_gmt":"2024-05-07T13:39:56","slug":"hydrocarbures-alnaft-convention-equinor","status":"publish","type":"post","link":"https:\/\/econostrum.info\/algerie\/hydrocarbures-alnaft-convention-equinor\/","title":{"rendered":"Hydrocarbures\u00a0: l\u2019Alnaft signe une convention avec le groupe norv\u00e9gien Equinor"},"content":{"rendered":"<p><strong>L\u2019Alg\u00e9rie attire de plus en plus d\u2019investisseurs dans le secteur des hydrocarbures. Plusieurs grandes entreprises \u00e9trang\u00e8res ont exprim\u00e9 leur int\u00e9r\u00eat pour le sous-sol alg\u00e9rien, alors que d&rsquo;autres sont d\u00e9j\u00e0 pr\u00e9sentes dans le pays.\u00a0<\/strong><\/p>\n<p>L&rsquo;Alg\u00e9rie a donc d\u00e9cid\u00e9 de renforcer sa coop\u00e9ration avec de <a href=\"https:\/\/econostrum.info\/algerie\/hydrocarbure-nabors-retour-algerie\/\" target=\"_blank\" rel=\"noopener\">groupes internationaux<\/a> dans le domaine des hydrocarbures. C&rsquo;est dans cette perspective que l\u2019Agence nationale pour la valorisation des ressources en hydrocarbures (Alnaft) a sign\u00e9 une convention avec la compagnie norv\u00e9gienne Equinor pour la r\u00e9alisation d\u2019une \u00e9tude sur le potentiel alg\u00e9rien en hydrocarbures.<\/p>\n<p>Cette convention a \u00e9t\u00e9 sign\u00e9e le 6 mai avec Equinor Algeria B.V, pour la r\u00e9alisation d\u2019une \u00e9tude sur le potentiel alg\u00e9rien en hydrocarbures, souligne le communiqu\u00e9 de Alnaft, qui indique que cette convention est d\u2019une dur\u00e9e de 18 mois, prolongeable d\u2019une ann\u00e9e. La convention a pour objet de \u00ab <em>d\u00e9finir les termes et conditions selon lesquels Equinor Algeria B.V r\u00e9alisera l\u2019\u00e9tude en question<\/em> \u00bb, explique encore le communiqu\u00e9.<\/p>\n<h2>Sonatrach et Equinor ont examin\u00e9 les opportunit\u00e9s d\u2019investissement, notamment dans les hydrocarbures<\/h2>\n<p>Alnaft a tenu \u00e0 rappeler, dans son communiqu\u00e9, que la soci\u00e9t\u00e9 norv\u00e9gienne Equinor Algeria B.V est pr\u00e9sente en Alg\u00e9rie depuis 2004. Il faut souligner qu&rsquo;avant la signature de la convention, <a href=\"https:\/\/www.energy.gov.dz\/?rubrique=le-ministre#:~:text=Tout%20au%20long%20de%20sa,projets%20industriels%20d&#039;importance%20nationale.\" target=\"_blank\" rel=\"noopener\">le ministre de l\u2019\u00c9nergie et des Mines,<\/a> M. Mohamed Arkab, a re\u00e7u le vice-pr\u00e9sident ex\u00e9cutif charg\u00e9 du dossier ext\u00e9rieur du groupe \u00e9nerg\u00e9tique norv\u00e9gien \u00ab Equinor \u00bb, \u200b\u200bM. Philippe Mathieu.<\/p>\n<p>Les deux parties ont examin\u00e9, lors de leur entretien, l\u2019\u00e9tat des relations de coop\u00e9ration bilat\u00e9rale dans le domaine de l\u2019\u00e9nergie, notamment l\u2019exploration et la production d\u2019hydrocarbures en Alg\u00e9rie, souligne le communiqu\u00e9 du minist\u00e8re. Elles ont \u00e9galement exprim\u00e9 leur satisfaction quant \u00e0 l\u2019excellence du partenariat existant entre Sonatrach et Equinor, notamment leur partenariat \u00e0 In Salah et In Amenas, indique la m\u00eame source.<\/p>\n<p>Concernant l&rsquo;avenir, les deux parties ont examin\u00e9 les opportunit\u00e9s d\u2019investissement permettant d\u2019\u00e9largir le partenariat existant entre la Sonatrach et Equinor et l\u2019\u00e9change d\u2019expertise et des exp\u00e9riences dans des domaines connexes, tels que le d\u00e9veloppement des puits, la r\u00e9duction de l\u2019impact de l\u2019industrie des hydrocarbures sur l\u2019environnement, la r\u00e9duction des \u00e9missions de dioxyde de carbone et le stockage de CCS, ajoute le communiqu\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Alg\u00e9rie attire de plus en plus d\u2019investisseurs dans le secteur des hydrocarbures. Plusieurs grandes entreprises \u00e9trang\u00e8res ont exprim\u00e9 leur int\u00e9r\u00eat pour le sous-sol alg\u00e9rien, alors que d&rsquo;autres sont d\u00e9j\u00e0 pr\u00e9sentes &#8230; <a title=\"Hydrocarbures\u00a0: l\u2019Alnaft signe une convention avec le groupe norv\u00e9gien Equinor\" class=\"read-more\" href=\"https:\/\/econostrum.info\/algerie\/hydrocarbures-alnaft-convention-equinor\/\" aria-label=\"En savoir plus sur Hydrocarbures\u00a0: l\u2019Alnaft signe une convention avec le groupe norv\u00e9gien Equinor\"> <\/a><\/p>\n","protected":false},"author":5,"featured_media":2279,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-2276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energie","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/2276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/comments?post=2276"}],"version-history":[{"count":0,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/2276\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media\/2279"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media?parent=2276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/categories?post=2276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/tags?post=2276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}