{"id":1735,"date":"2024-04-07T11:47:27","date_gmt":"2024-04-07T10:47:27","guid":{"rendered":"https:\/\/econostrum.info\/algerie\/?p=1735"},"modified":"2024-04-07T11:47:27","modified_gmt":"2024-04-07T10:47:27","slug":"prix-denrees-alimentaires-courbe-haussiere","status":"publish","type":"post","link":"https:\/\/econostrum.info\/algerie\/prix-denrees-alimentaires-courbe-haussiere\/","title":{"rendered":"Apr\u00e8s plusieurs mois de baisse, les prix des denr\u00e9es alimentaires reprennent avec leur courbe haussi\u00e8re (FAO)"},"content":{"rendered":"<p><strong>L&rsquo;\u00e9conomie mondiale a \u00e9t\u00e9 impact\u00e9e par plusieurs crises successives. Apr\u00e8s la crise sanitaire, la guerre en Ukraine a perturb\u00e9 les march\u00e9s et a fait flamber les prix, notamment des denr\u00e9es alimentaires et de l&rsquo;\u00e9nergie. Cette inflation a entam\u00e9 une courbe baissi\u00e8re depuis le mois de juillet 2023 concernant les denr\u00e9es alimentaires.<\/strong><\/p>\n<p>Cependant, cette tendance baissi\u00e8re s&rsquo;est renvers\u00e9e le mois de mars 2024. L\u2019Organisation des Nations Unies pour l\u2019alimentation et l\u2019agriculture (FAO) souligne dans son rapport mensuel que son indice du prix des huiles v\u00e9g\u00e9tales a bondi de 8 % en mars. Il a atteint \u00ab <em>son record sur un an<\/em> \u00bb, indique le rapport. \u00ab <em>Les cotations des huiles de palme, de soja, de tournesol et de colza ont toutes augment\u00e9<\/em> \u00bb, souligne encore le rapport.<\/p>\n<p>Au mois de mars 2024, les prix sont donc repartis \u00e0 la hausse. La FAO explique que l&rsquo;envol\u00e9 des prix mondiaux des huiles v\u00e9g\u00e9tales n\u2019a pas \u00e9t\u00e9 compens\u00e9 par la nouvelle baisse des cours des c\u00e9r\u00e9ales. En d\u00e9tail, l\u2019indice FAO a augment\u00e9 de 1,1 % en mars par rapport \u00e0 f\u00e9vrier. Toutefois, la tendance est toujours \u00e0 la baisse des prix sur un an avec un repli de 7,7 % par rapport \u00e0 mars 2023.<\/p>\n<h2>Les denr\u00e9es alimentaires en baisse<\/h2>\n<p>L&rsquo;indice FAO qui suit la variation des cours internationaux d\u2019un panier de produits de base a donc \u00e9t\u00e9 impact\u00e9 par la hausse des cours des huiles v\u00e9g\u00e9tales qui a port\u00e9 l\u2019augmentation des prix en mars. Le rapport explique que l\u2019huile de palme a souffert de r\u00e9coltes saisonni\u00e8res \u00ab<em> moins bonnes que pr\u00e9vu<\/em> \u00bb. Ce facteur conjugu\u00e9 \u00e0 une forte demande en Asie du Sud-Est a fait que les prix flambent.<\/p>\n<p>Par ailleurs, la FAO indique qu&rsquo;en parall\u00e8le \u00e0 cette flamb\u00e9e, les produits laitiers et la viande ont connu une hausse de 2,9 % et 1,7 % respectivement, alors que le prix des c\u00e9r\u00e9ales a baiss\u00e9 de 2,6 % en mars. Il est donc de \u00ab <em>20% en dessous de sa valeur de mars 2022 et de 2,6% par rapport \u00e0 f\u00e9vrier 2024<\/em> \u00bb. \u00ab <em>Ce recul est d\u00fb \u00e0 la diminution <a href=\"https:\/\/econostrum.info\/algerie\/exportations-ble-francais-algerie-chute\/\" target=\"_blank\" rel=\"noopener\">des prix mondiaux du bl\u00e9,<\/a> en raison de la forte concurrence \u00e0 l\u2019exportation<\/em> \u00bb entre l\u2019Union europ\u00e9enne, la Russie et les \u00c9tats-Unis, explique le rapport.<\/p>\n<p>De son c\u00f4t\u00e9, le prix du riz a enregistr\u00e9 un recul de 1,7 % en mars, tandis que le cours du ma\u00efs a augment\u00e9, \u00ab <em>en partie \u00e0 cause de probl\u00e8mes logistiques en Ukraine<\/em> \u00bb, indique le rapport de la<a href=\"https:\/\/www.fao.org\/home\/fr\" target=\"_blank\" rel=\"noopener\"> FAO<\/a> qui souligne \u00e9galement que les prix du sucre ont enregistr\u00e9 un recul de 5,4 %.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00e9conomie mondiale a \u00e9t\u00e9 impact\u00e9e par plusieurs crises successives. Apr\u00e8s la crise sanitaire, la guerre en Ukraine a perturb\u00e9 les march\u00e9s et a fait flamber les prix, notamment des denr\u00e9es &#8230; <a title=\"Apr\u00e8s plusieurs mois de baisse, les prix des denr\u00e9es alimentaires reprennent avec leur courbe haussi\u00e8re (FAO)\" class=\"read-more\" href=\"https:\/\/econostrum.info\/algerie\/prix-denrees-alimentaires-courbe-haussiere\/\" aria-label=\"En savoir plus sur Apr\u00e8s plusieurs mois de baisse, les prix des denr\u00e9es alimentaires reprennent avec leur courbe haussi\u00e8re (FAO)\"> <\/a><\/p>\n","protected":false},"author":5,"featured_media":1737,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1735","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/1735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/comments?post=1735"}],"version-history":[{"count":0,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/1735\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media\/1737"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media?parent=1735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/categories?post=1735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/tags?post=1735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}