{"id":1531,"date":"2024-03-25T15:17:39","date_gmt":"2024-03-25T14:17:39","guid":{"rendered":"https:\/\/econostrum.info\/algerie\/?p=1531"},"modified":"2024-03-25T15:17:39","modified_gmt":"2024-03-25T14:17:39","slug":"energies-fossiles-sg-opep","status":"publish","type":"post","link":"https:\/\/econostrum.info\/algerie\/energies-fossiles-sg-opep\/","title":{"rendered":"Campagnes contre les \u00e9nergies fossiles : le SG de l&rsquo;Opep met en garde"},"content":{"rendered":"<p><strong>Ces derni\u00e8res ann\u00e9es, les \u00e9nergies fossiles sont remises en cause, notamment en raison du r\u00e9chauffement climatique. Tenues pour responsables de la hausse des \u00e9missions de gaz carbonique, elles sont dans le collimateur de plusieurs organisations, \u00c9tats et militants \u00e9cologistes.<\/strong><\/p>\n<p>Le d\u00e9bat fait rage en tout cas autour de l&rsquo;avenir des \u00e9nergies fossiles. Certains dirigeants, dont Emmanuel Macron, ont appel\u00e9 \u00e0 sortir du charbon avant 2030. D&rsquo;autres veulent diminuer les investissements dans les hydrocarbures et mettre fin aux moteurs thermiques dans des \u00e9ch\u00e9anciers tr\u00e8s courts. Pour les d\u00e9tracteurs des \u00e9nergies fossiles, il est temps de passer aux alternatives renouvelables moins polluantes.<\/p>\n<p>Le secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;Opep n&rsquo;est toutefois pas d&rsquo;accord avec cette perspective. Il a tenu \u00e0 mettre en garde ceux qui se battent contre les \u00e9nergies fossiles. Pour ce responsable, un monde sans p\u00e9trole aura des cons\u00e9quences graves. \u00c9conomie \u00e0 l\u2019arr\u00eat, croissance frein\u00e9e, sant\u00e9 en danger, trains et bateaux bloqu\u00e9s aux quais, p\u00e9nurie des produits alimentaires et du mat\u00e9riel m\u00e9dical, industrie num\u00e9rique et \u00e9lectronique en berne, c&rsquo;est ce qui r\u00e9sultera du sc\u00e9nario d\u00e9fendu par les d\u00e9tracteurs des \u00e9nergies fossiles, indique le SG de l&rsquo;Opep.<\/p>\n<h2>Tout le monde veut voir les \u00e9missions de gaz \u00e0 effet de serre r\u00e9duites<\/h2>\n<p>Pour Haitham Al Ghais, les courants anti-fossile ne cessent de vendre au monde une image \u00ab <em>idyllique<\/em> \u00bb d\u2019une plan\u00e8te sans l\u2019or noir. Le p\u00e9trole reste donc une \u00e9nergie cruciale pour l\u2019\u00e9conomie mondiale. \u00ab <em>Nous devons \u00eatre prudents de ne pas mettre le pr\u00e9sent en danger sous pr\u00e9texte de sauver le futur. Il est crucial que nous appr\u00e9hendions tous les innombrables avantages que le p\u00e9trole et les produits p\u00e9troliers qui en d\u00e9coulent continuent \u00e0 fournir \u00e0 notre civilisation<\/em> \u00bb, affirme le SG de l&rsquo;Opep dans une contribution.<\/p>\n<p>Haitham Al Ghais explique que sans l\u2019or noir, l\u2019humanit\u00e9 se retrouverait immobile, sans nourriture et sans acc\u00e8s aux soins, en raison de la p\u00e9nurie en composant et intrants p\u00e9troliers. \u00ab<em> Un monde sans k\u00e9ros\u00e8ne, essence ou diesel ! Les voitures, les bus, les camions et autres v\u00e9hicules \u00e0 moteur \u00e0 combustion interne seraient bloqu\u00e9s. Les avions clou\u00e9s au sol. Les transports ferroviaires de marchandises et de voyageurs aliment\u00e9s par le diesel s\u2019arr\u00eateraient. Les travailleurs se retrouveraient bloqu\u00e9s chez eux, L\u2019industrie maritime, pivot crucial pour le commerce mondial et le transport de marchandises et de passagers, subirait des ravages incommensurables<\/em> \u00bb, \u00e9crit-il.<\/p>\n<p>\u00ab <em>Malgr\u00e9 ces r\u00e9alit\u00e9s, des appels sont lanc\u00e9s pour<a href=\"https:\/\/econostrum.info\/algerie\/previsions-demande-petrole-aie-opep\/\" target=\"_blank\" rel=\"noopener\"> stopper le p\u00e9trole<\/a><\/em> \u00bb, fustige ce haut responsable qui rappelle les slogans, tels que \u00ab <em>Gardez-le au sous-sol<\/em> \u00bb ou les appels \u00e0 \u00ab <em>ne pas investir dans de nouveaux projets p\u00e9troliers et gaziers<\/em> \u00bb sous pr\u00e9texte de lutte pour le climat.<\/p>\n<p>Cette d\u00e9marche vise \u00e0 priver l\u2019humanit\u00e9 d\u2019un combustible aussi important pour le d\u00e9veloppement \u00e9conomique des pays et la prosp\u00e9rit\u00e9 des peuples, selon le secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;<a href=\"https:\/\/www.opec.org\/opec_web\/en\/\" target=\"_blank\" rel=\"noopener\">Opep<\/a> qui souligne que \u00ab <em>bien \u00e9videmment, tout le monde veut voir les \u00e9missions de gaz \u00e0 effet de serre r\u00e9duites. L\u2019Opep estime que les solutions technologiques et les am\u00e9liorations d\u2019efficacit\u00e9 peuvent jouer un r\u00f4le vital. L\u2019industrie p\u00e9troli\u00e8re est d\u00e9j\u00e0 proactive \u00e0 cet \u00e9gard<\/em> \u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ces derni\u00e8res ann\u00e9es, les \u00e9nergies fossiles sont remises en cause, notamment en raison du r\u00e9chauffement climatique. Tenues pour responsables de la hausse des \u00e9missions de gaz carbonique, elles sont dans &#8230; <a title=\"Campagnes contre les \u00e9nergies fossiles : le SG de l&rsquo;Opep met en garde\" class=\"read-more\" href=\"https:\/\/econostrum.info\/algerie\/energies-fossiles-sg-opep\/\" aria-label=\"En savoir plus sur Campagnes contre les \u00e9nergies fossiles : le SG de l&rsquo;Opep met en garde\"> <\/a><\/p>\n","protected":false},"author":5,"featured_media":1534,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-1531","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energie","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/1531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/comments?post=1531"}],"version-history":[{"count":0,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/1531\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media\/1534"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media?parent=1531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/categories?post=1531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/tags?post=1531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}