{"id":1468,"date":"2024-03-21T15:00:02","date_gmt":"2024-03-21T14:00:02","guid":{"rendered":"https:\/\/econostrum.info\/algerie\/?p=1468"},"modified":"2024-03-21T13:15:58","modified_gmt":"2024-03-21T12:15:58","slug":"risque-secheresse-algerie","status":"publish","type":"post","link":"https:\/\/econostrum.info\/algerie\/risque-secheresse-algerie\/","title":{"rendered":"Risque important de s\u00e9cheresse en Alg\u00e9rie, selon une \u00e9tude du JRC"},"content":{"rendered":"<p><strong>Le r\u00e9chauffement climatique est une r\u00e9alit\u00e9 concr\u00e8te en Afrique du Nord. Depuis quelques ann\u00e9es, les pays de cette r\u00e9gion connaissent des \u00e9pisodes r\u00e9currents de s\u00e9cheresse et des records de temp\u00e9ratures. Les pr\u00e9cipitations se font rares, et certaines saisons ont carr\u00e9ment disparu, notamment au Maroc et en Alg\u00e9rie.<\/strong><\/p>\n<p>Il faut dire que la situation est la m\u00eame dans le pourtour m\u00e9diterran\u00e9en, selon un rapport du Centre commun de recherche de la Commission europ\u00e9enne (JRC).<\/p>\n<p>Les temp\u00e9ratures persistantes au-dessus de la moyenne, les vagues de chaleur et les faibles pr\u00e9cipitations ont entra\u00een\u00e9 des conditions de s\u00e9cheresse s\u00e9v\u00e8res dans la r\u00e9gion m\u00e9diterran\u00e9enne, touchant de nombreuses r\u00e9gions du sud de l\u2019Italie, du sud de l\u2019Espagne, de Malte, du Maroc, de l\u2019Alg\u00e9rie et de la Tunisie, selon le m\u00eame rapport.<\/p>\n<p><em>\u00ab Apr\u00e8s les temp\u00e9ratures extr\u00eamement \u00e9lev\u00e9es qui ont marqu\u00e9 l\u2019ann\u00e9e 2023, 2024 d\u00e9bute dans des conditions critiques de s\u00e9cheresse dans le bassin m\u00e9diterran\u00e9en \u00bb, <\/em>avertit le JRC. Ce rapport met en avant la situation qui s&rsquo;aggrave de plus en plus en Afrique du Nord.<\/p>\n<h2>Le dessalement de l&rsquo;eau de mer, une solution contre la s\u00e9cheresse<\/h2>\n<p>Il est \u00e9galement r\u00e9v\u00e9l\u00e9 que le Maroc fait face \u00e0 sa sixi\u00e8me ann\u00e9e avec peu de pr\u00e9cipitations. Ce qui a de grandes cons\u00e9quences sur le niveau de remplissage moyen des barrages, qui a atteint difficilement 23%. Dans ce pays, les pluies sont inf\u00e9rieures de 70% \u00e0 la moyenne depuis septembre 2023.<\/p>\n<p>L&rsquo;Alg\u00e9rie conna\u00eet une situation similaire. Le pays a travers\u00e9 une longue p\u00e9riode de s\u00e9cheresse ayant impact\u00e9 fortement les barrages et les approvisionnements en eau potable. Toutefois, l<a href=\"https:\/\/econostrum.info\/algerie\/meteo-alertes-neige-verglas-vents-violents\/\" target=\"_blank\" rel=\"noopener\">es pluies et les neiges<\/a> du mois de f\u00e9vrier dernier ont \u00e9t\u00e9 salutaires. Elles ont permis d\u2019augmenter, m\u00eame faiblement, le niveau de remplissage des barrages (avec un taux moyen de 40,85%).<\/p>\n<p>Le <a href=\"https:\/\/commission.europa.eu\/about-european-commission\/departments-and-executive-agencies\/joint-research-centre_fr\" target=\"_blank\" rel=\"noopener\">JRC<\/a> a soulign\u00e9 l\u2019importance de l\u2019att\u00e9nuation du changement climatique et des mesures d\u2019adaptation pour la gestion de l\u2019eau et les secteurs d\u00e9pendants de l\u2019eau, comme l\u2019agriculture et la production d\u2019eau potable, face \u00e0 l\u2019aggravation de la situation et aux impacts du r\u00e9chauffement climatique.<\/p>\n<p>Pour faire face \u00e0 cette situation critique, les pays de l&rsquo;Afrique du Nord ont mis\u00e9 sur le dessalement de l&rsquo;eau de mer. En effet, pour compenser le d\u00e9ficit en pluviom\u00e9trie, huit usines dessalement d\u2019eau de mer au Maroc, neuf en Alg\u00e9rie et sept en Tunisie ont \u00e9t\u00e9 mises en place.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le r\u00e9chauffement climatique est une r\u00e9alit\u00e9 concr\u00e8te en Afrique du Nord. Depuis quelques ann\u00e9es, les pays de cette r\u00e9gion connaissent des \u00e9pisodes r\u00e9currents de s\u00e9cheresse et des records de temp\u00e9ratures. &#8230; <a title=\"Risque important de s\u00e9cheresse en Alg\u00e9rie, selon une \u00e9tude du JRC\" class=\"read-more\" href=\"https:\/\/econostrum.info\/algerie\/risque-secheresse-algerie\/\" aria-label=\"En savoir plus sur Risque important de s\u00e9cheresse en Alg\u00e9rie, selon une \u00e9tude du JRC\"> <\/a><\/p>\n","protected":false},"author":5,"featured_media":1467,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-1468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meteo-algerie","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/1468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/comments?post=1468"}],"version-history":[{"count":0,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/1468\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media\/1467"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media?parent=1468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/categories?post=1468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/tags?post=1468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}