{"id":101237,"date":"2025-06-12T13:11:03","date_gmt":"2025-06-12T12:11:03","guid":{"rendered":"https:\/\/econostrum.info\/algerie\/?p=101237"},"modified":"2025-06-12T13:11:06","modified_gmt":"2025-06-12T12:11:06","slug":"gouvernement-projet-banque-postale","status":"publish","type":"post","link":"https:\/\/econostrum.info\/algerie\/gouvernement-projet-banque-postale\/","title":{"rendered":"Le gouvernement examine le projet de cr\u00e9ation d&rsquo;une banque postale"},"content":{"rendered":"<p><strong>Le projet de cr\u00e9ation d\u2019une banque postale en Alg\u00e9rie, maintes fois \u00e9voqu\u00e9, mais jamais concr\u00e9tis\u00e9, vient de franchir une \u00e9tape d\u00e9cisive. Lors d\u2019une r\u00e9union gouvernementale qui au lieu le 11 juin, ce chantier a \u00e9t\u00e9 officiellement examin\u00e9, selon un communiqu\u00e9 diffus\u00e9 par les services du Premier minist\u00e8re.<\/strong><\/p>\n<p>\u00ab Dans le cadre du renforcement et de la modernisation des services bancaires, le gouvernement a entendu une communication sur le projet de cr\u00e9ation d\u2019une banque postale sous la forme d\u2019une filiale d\u2019Alg\u00e9rie Poste \u00bb indique un <a href=\"https:\/\/www.facebook.com\/share\/1EDMqnSPGu\/\" target=\"_blank\" rel=\"noopener\">communiqu\u00e9 du premier minist\u00e8re<\/a>. Cette future entit\u00e9 bancaire vise \u00e0 \u00e9largir l\u2019acc\u00e8s aux services financiers en ciblant les zones les moins desservies et les populations peu ou pas bancaris\u00e9es.<\/p>\n<p>Pens\u00e9e comme un levier de d\u00e9mocratisation de l\u2019acc\u00e8s aux services bancaires, cette banque postale jouera un r\u00f4le compl\u00e9mentaire aux \u00e9tablissements traditionnels. Son activit\u00e9, centr\u00e9e sur des services d\u2019int\u00e9r\u00eat public plus que sur une logique commerciale, permettrait de proposer des produits bancaires essentiels (\u00e9pargne, paiement, transfert, etc.) \u00e0 des co\u00fbts plus accessibles. \u00ab Ce projet (&#8230;) contribuera \u00e0 rapprocher les services bancaires des citoyens, \u00e0 attirer les d\u00e9p\u00f4ts financiers et \u00e0 am\u00e9liorer les services financiers universels et diversifi\u00e9s \u00bb indique le m\u00eame communiqu\u00e9.<\/p>\n<h2>La banque postale, un outil pour renforcer l\u2019inclusion financi\u00e8re<\/h2>\n<p>Gr\u00e2ce au r\u00e9seau dense de bureaux de poste d\u00e9ploy\u00e9s dans tout le pays, la banque postale pourra compter sur une pr\u00e9sence territoriale \u00e9tendue. En 2024, l\u2019Alg\u00e9rie comptait plus de 4 332 bureaux de poste actifs, avec une densit\u00e9 postale d\u2019un bureau pour 10 500 habitants. Ce maillage constitue une base solide pour faciliter la bancarisation des populations \u00e9loign\u00e9es des circuits classiques. Par ailleurs, le nombre de cartes Edahabia, d\u00e9passant les 16 millions selon les chiffres du Groupement d\u2019int\u00e9r\u00eat \u00e9conomique mon\u00e9tique, t\u00e9moigne du potentiel \u00e0 exploiter.<\/p>\n<p>Le gouvernement esp\u00e8re que cette nouvelle banque contribuera \u00e0 capter une part de la masse mon\u00e9taire encore largement en circulation hors des circuits officiels. En r\u00e9int\u00e9grant ces fonds dans le syst\u00e8me bancaire, elle participerait \u00e0 am\u00e9liorer <a href=\"https:\/\/econostrum.info\/algerie\/blanchiment-dargent-algerie-gafi\/\" target=\"_blank\" rel=\"noopener\">la stabilit\u00e9 \u00e9conomique et la transparence des flux financiers<\/a>. La Banque centrale estime que le taux de bancarisation reste en dessous des standards, bien que des progr\u00e8s soient enregistr\u00e9s. En 2023, le pays comptait 3,41 comptes par personne en \u00e2ge de travailler, contre 3,26 en 2022.<\/p>\n<p>La future banque postale pourrait donc agir comme un catalyseur de modernisation et d\u2019\u00e9quit\u00e9 financi\u00e8re. En compl\u00e9ment des banques classiques, elle offrirait des services simples et s\u00e9curis\u00e9s \u00e0 une population plus large, participant ainsi \u00e0 un objectif plus large de r\u00e9forme bancaire. En donnant son feu vert \u00e0 ce projet, le gouvernement affiche sa volont\u00e9 d\u2019adapter l\u2019infrastructure financi\u00e8re du pays aux besoins d\u2019une soci\u00e9t\u00e9 en pleine transformation.<\/p>\n<p>\u00a0<\/p>\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"fr\" dir=\"ltr\">Le Gouvernement examine le projet de cr\u00e9ation d\u2019une banque postale, une filiale d\u2019Alg\u00e9rie Poste <a href=\"https:\/\/t.co\/tfwQJJubP7\">https:\/\/t.co\/tfwQJJubP7<\/a><\/p>&mdash; algerie-eco (@algerie_eco) <a href=\"https:\/\/twitter.com\/algerie_eco\/status\/1932857979532886184?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">June 11, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Le projet de la cr\u00e9ation d&rsquo;une banque postale fait son chemin en Alg\u00e9rie. <\/p>\n","protected":false},"author":5,"featured_media":99984,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-101237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/101237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/comments?post=101237"}],"version-history":[{"count":0,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/101237\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media\/99984"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media?parent=101237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/categories?post=101237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/tags?post=101237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}