{"id":100807,"date":"2025-04-28T12:30:52","date_gmt":"2025-04-28T11:30:52","guid":{"rendered":"https:\/\/econostrum.info\/algerie\/?p=100807"},"modified":"2025-04-28T12:30:55","modified_gmt":"2025-04-28T11:30:55","slug":"seniors-carte-privileges","status":"publish","type":"post","link":"https:\/\/econostrum.info\/algerie\/seniors-carte-privileges\/","title":{"rendered":"S\u00e9niors : cette carte permet aux personnes de plus de 65 ans d&rsquo;acc\u00e9der \u00e0 plusieurs privil\u00e8ges en Alg\u00e9rie"},"content":{"rendered":"<p><strong>\u00c0 l&rsquo;occasion de la Journ\u00e9e nationale des personnes \u00e2g\u00e9es, le minist\u00e8re de la Solidarit\u00e9 nationale, de la Famille et de la Condition de la femme a pr\u00e9sent\u00e9 plusieurs mesures pour am\u00e9liorer le quotidien des seniors de plus de 65 ans. <\/strong><\/p>\n<p>Ces initiatives incluent notamment l\u2019acc\u00e8s \u00e0 divers services culturels et sociaux \u00e0 des tarifs r\u00e9duits, ainsi que la cr\u00e9ation d\u2019une carte d\u00e9di\u00e9e pour faciliter l\u2019acc\u00e8s \u00e0 ces avantages. Dans une d\u00e9claration t\u00e9l\u00e9vis\u00e9e, Soumeya Oulmane, directrice de la protection des personnes \u00e2g\u00e9es au sein du minist\u00e8re, a pr\u00e9cis\u00e9 que trois conventions de coop\u00e9ration \u00e9taient en cours de finalisation.<\/p>\n<p>Ces accords, qui seront sign\u00e9s avec le minist\u00e8re du Tourisme, le minist\u00e8re de la Culture et des Arts, la Caisse nationale des assurances sociales (CNAS) et l\u2019Agence de d\u00e9veloppement social, visent \u00e0 offrir des privil\u00e8ges concrets aux seniors, dans le but de renforcer leur inclusion sociale.<\/p>\n<h2>Des avantages concrets pour les s\u00e9niors de plus de 65 ans<\/h2>\n<p>Les seniors de plus de 65 ans b\u00e9n\u00e9ficieront de plusieurs avantages gr\u00e2ce \u00e0 ces nouvelles conventions. Parmi les mesures phares, on note l&rsquo;acc\u00e8s gratuit aux mus\u00e9es nationaux, offrant ainsi la possibilit\u00e9 aux a\u00een\u00e9s de s&rsquo;enrichir culturellement. Les seniors auront \u00e9galement droit \u00e0 une r\u00e9duction de 50 % sur les services de tourisme thermal, leur permettant de profiter des bienfaits de ces soins sp\u00e9cifiques.<\/p>\n<p>D&rsquo;autres initiatives incluent des r\u00e9ductions sur les billets pour les th\u00e9\u00e2tres et les cin\u00e9mas publics, afin de favoriser l\u2019acc\u00e8s \u00e0 la culture pour les personnes \u00e2g\u00e9es. De plus, un espace d\u00e9di\u00e9 aux seniors, appel\u00e9 \u00ab le couloir vert \u00bb, sera mis en place dans les agences de la <a href=\"https:\/\/cnas.dz\/\" target=\"_blank\" rel=\"noopener\">CNAS<\/a> pour mieux r\u00e9pondre \u00e0 leurs besoins. Des r\u00e9ductions seront \u00e9galement propos\u00e9es sur l\u2019h\u00e9bergement touristique pour les voyages organis\u00e9s \u00e0 destination des seniors, avec des exon\u00e9rations sur certains d\u00e9placements.<\/p>\n<p>Soumeya Oulmane a pr\u00e9cis\u00e9 que toute personne ayant atteint l&rsquo;\u00e2ge de 65 ans pourra obtenir cette carte sp\u00e9ciale en se rendant dans les directions de l&rsquo;action sociale de sa wilaya. La proc\u00e9dure d\u2019inscription est simple et accessible, permettant ainsi \u00e0 tous les seniors d\u2019acc\u00e9der \u00e0 ces avantages sans difficult\u00e9s.<\/p>\n<p>Cette carte du senior deviendra un outil cl\u00e9 pour garantir l&rsquo;acc\u00e8s facilit\u00e9 aux services offerts par ces nouvelles conventions, r\u00e9pondant ainsi \u00e0 un besoin croissant d&rsquo;inclusion sociale et culturelle pour cette tranche de la population. Le minist\u00e8re de la Solidarit\u00e9 nationale pr\u00e9voit \u00e9galement d&rsquo;\u00e9tendre ces avantages \u00e0 d\u2019autres secteurs dans un futur proche, afin d\u2019offrir une gamme plus compl\u00e8te de <a href=\"https:\/\/econostrum.info\/algerie\/retraite-algerie-nouveau-service-cnr\/\" target=\"_blank\" rel=\"noopener\">services adapt\u00e9s aux personnes \u00e2g\u00e9es<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les s\u00e9niors de plus de 65 ans devront b\u00e9n\u00e9ficier de plusieurs avantages gr\u00e2ce \u00e0 une nouvelle carte qui sera mise \u00e0 leur disposition.  <\/p>\n","protected":false},"author":5,"featured_media":100808,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-100807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-retraite","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/100807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/comments?post=100807"}],"version-history":[{"count":0,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/100807\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media\/100808"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media?parent=100807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/categories?post=100807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/tags?post=100807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}