{"id":100368,"date":"2025-02-25T16:00:00","date_gmt":"2025-02-25T15:00:00","guid":{"rendered":"https:\/\/econostrum.info\/algerie\/?p=100368"},"modified":"2025-02-25T15:30:31","modified_gmt":"2025-02-25T14:30:31","slug":"ramadan-horaires-institutions-publiques","status":"publish","type":"post","link":"https:\/\/econostrum.info\/algerie\/ramadan-horaires-institutions-publiques\/","title":{"rendered":"Ramadan 2025\u00a0: voici les horaires de travail des institutions publiques"},"content":{"rendered":"<p><strong>La Direction g\u00e9n\u00e9rale de la fonction publique et de la r\u00e9forme administrative a pr\u00e9cis\u00e9 le lundi 24 f\u00e9vrier les horaires de travail qui seront appliqu\u00e9s dans les institutions publiques et administrations pendant le mois du ramadan.<\/strong><\/p>\n<p>Dans les wilayas du sud, \u00e0 savoir Adrar, Tamanrasset, Illizi, Tindouf, B\u00e9char, Ouargla, Gharda\u00efa, Laghouat, Biskra, El Oued, Timimoun, Bordj Badji Mokhtar, Ouled Djellal, B\u00e9ni Abb\u00e8s, In Salah, In Guezzam, Touggourt, Djanet, El Meghair et El Menia, les employ\u00e9s travailleront de 8 h 00 \u00e0 15 h 00. Dans les autres wilayas du pays, les horaires seront fix\u00e9s de 8h30 \u00e0 15h30. La direction a \u00e9galement pr\u00e9cis\u00e9 que \u00ab les horaires de travail normaux seront r\u00e9tablis apr\u00e8s l\u2019A\u00efd el-Fitr \u00bb.<\/p>\n<h2>Des mesures pour assurer l\u2019approvisionnement du march\u00e9 durant le mois de Ramadan<\/h2>\n<p>Afin de garantir <a href=\"https:\/\/econostrum.info\/algerie\/ramadan-2025-marche-inonde-viande\/\" target=\"_blank\" rel=\"noopener\">une disponibilit\u00e9 suffisante des produits alimentaires<\/a> pendant le mois sacr\u00e9, le minist\u00e8re du Commerce int\u00e9rieur et de la R\u00e9gulation du march\u00e9 avait r\u00e9cemment annonc\u00e9 l\u2019importation de 28 000 tonnes de viande. Ce volume sera r\u00e9parti entre 13 000 tonnes de viande rouge et 15 000 tonnes de viande blanche, en compl\u00e9ment d\u2019une production locale mensuelle estim\u00e9e \u00e0 35 000 tonnes. Mohamed Mezghache, Directeur g\u00e9n\u00e9ral du contr\u00f4le \u00e9conomique, a pr\u00e9cis\u00e9 que ces importations incluront des viandes bovines et ovines sous forme de carcasses, ainsi que des animaux destin\u00e9s \u00e0 l\u2019abattage local.<\/p>\n<p>D\u2019autres mesures concernent l\u2019augmentation de la production de produits essentiels comme l\u2019huile, le sucre et le lait. La capacit\u00e9 de production quotidienne d\u2019huile passera ainsi de 1 800 tonnes \u00e0 3 600 tonnes, tandis que celle du sucre passera de 1 900 tonnes \u00e0 4 200 tonnes. Les disponibilit\u00e9s de poudre de lait seront \u00e9galement renforc\u00e9es pour atteindre 24 000 tonnes par mois.<\/p>\n<p>Le minist\u00e8re du Commerce pr\u00e9voit \u00e9galement un contr\u00f4le strict des prix et de la qualit\u00e9 des produits, avec des inspections men\u00e9es dans les unit\u00e9s de production, chez les grossistes et les d\u00e9taillants. L\u2019objectif est de limiter toute sp\u00e9culation et de garantir un approvisionnement stable durant tout le mois du ramadan.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les institutions publiques adapteront leurs horaires durant le mois de Ramadan<\/p>\n","protected":false},"author":5,"featured_media":100369,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-100368","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/100368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/comments?post=100368"}],"version-history":[{"count":0,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/100368\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media\/100369"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media?parent=100368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/categories?post=100368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/tags?post=100368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}