{"id":100268,"date":"2025-02-13T11:21:00","date_gmt":"2025-02-13T10:21:00","guid":{"rendered":"https:\/\/econostrum.info\/algerie\/?p=100268"},"modified":"2025-02-13T10:51:13","modified_gmt":"2025-02-13T09:51:13","slug":"hydrogene-liquide-lespagnol-coolergy","status":"publish","type":"post","link":"https:\/\/econostrum.info\/algerie\/hydrogene-liquide-lespagnol-coolergy\/","title":{"rendered":"Hydrog\u00e8ne liquide : l\u2019espagnol Coolergy exprime son int\u00e9r\u00eat pour une coop\u00e9ration avec l\u2019Alg\u00e9rie"},"content":{"rendered":"<p><strong>L&rsquo;Alg\u00e9rie compte bien exploiter ses ressources en hydrog\u00e8ne. Le 12 f\u00e9vrier 2025, le secr\u00e9taire d&rsquo;\u00c9tat charg\u00e9 des \u00e9nergies renouvelables en Alg\u00e9rie, Noureddine Yassa\u00e2, a rencontr\u00e9 Kirill Lyats, le PDG de l&rsquo;entreprise espagnole Coolergy. <\/strong><\/p>\n<p>Ce groupe sp\u00e9cialis\u00e9 dans la technologie cryog\u00e9nique et la liqu\u00e9faction de l\u2019hydrog\u00e8ne a exprim\u00e9 son int\u00e9r\u00eat pour une coop\u00e9ration avec l\u2019Alg\u00e9rie, afin de d\u00e9velopper et exporter de l\u2019hydrog\u00e8ne liquide, un secteur prometteur dans la transition \u00e9nerg\u00e9tique. Les discussions ont port\u00e9 sur la production d\u2019hydrog\u00e8ne vert et bleu en Alg\u00e9rie, ainsi que sur les technologies de liqu\u00e9faction et de stockage.<\/p>\n<p>L&rsquo;Alg\u00e9rie, avec son potentiel naturel et sa position g\u00e9ographique strat\u00e9gique, pourrait jouer un r\u00f4le majeur dans le <a href=\"https:\/\/econostrum.info\/algerie\/energies-bosch-interesse-lalgerie\/\" target=\"_blank\" rel=\"noopener\">d\u00e9veloppement de l&rsquo;hydrog\u00e8ne<\/a> \u00e0 l&rsquo;\u00e9chelle mondiale. Noureddine Yassa\u00e2 a soulign\u00e9 que l\u2019objectif du gouvernement alg\u00e9rien est de faire du pays un acteur central de ce secteur, en vue de fournir de l\u2019hydrog\u00e8ne \u00e0 des march\u00e9s cl\u00e9s comme l\u2019Europe et l&rsquo;Afrique.<\/p>\n<h2>Un partenariat pour la liqu\u00e9faction de l&rsquo;hydrog\u00e8ne<\/h2>\n<p>Le <a href=\"https:\/\/www.energy.gov.dz\/?rubrique=le-ministre#:~:text=En%20date%20du%2018%20novembre,1966%20%C3%A0%20Hussein%20Dey%2DAlger.\" target=\"_blank\" rel=\"noopener\">secr\u00e9taire d&rsquo;\u00c9tat charg\u00e9 des \u00e9nergies renouvelables<\/a> a \u00e9galement insist\u00e9 sur la n\u00e9cessit\u00e9 de renforcer les infrastructures pour soutenir cette nouvelle industrie. \u00ab Nous devons d\u00e9velopper des infrastructures solides pour garantir la production, la liqu\u00e9faction et le transport de l\u2019hydrog\u00e8ne, et ce partenariat avec Coolergy est essentiel pour atteindre cet objectif \u00bb, a d\u00e9clar\u00e9 Yassa\u00e2 lors de la rencontre.<\/p>\n<p>Pour Coolergy, ce partenariat est une occasion d\u2019\u00e9largir son r\u00e9seau d\u2019infrastructures et de profiter de l\u2019expertise alg\u00e9rienne dans le domaine des \u00e9nergies renouvelables. Le PDG de Coolergy, Kirill Lyats, a expliqu\u00e9 que \u00ab l\u2019Alg\u00e9rie est un partenaire strat\u00e9gique pour nos projets de production d&rsquo;hydrog\u00e8ne liquide. Nous souhaitons \u00e9tablir des centres de production en Afrique et en Europe, et l\u2019Alg\u00e9rie est bien plac\u00e9e pour jouer un r\u00f4le majeur dans cette dynamique \u00bb.<\/p>\n<p>Les deux parties ont aussi discut\u00e9 des applications concr\u00e8tes de l\u2019hydrog\u00e8ne liquide, particuli\u00e8rement dans le secteur du transport. L\u2019hydrog\u00e8ne pourrait ainsi alimenter des trains, bus, camions et navires, notamment dans le but de r\u00e9duire les \u00e9missions de gaz \u00e0 effet de serre dans des secteurs difficiles \u00e0 d\u00e9carboner.<\/p>\n<p>Le projet pourrait \u00e9galement stimuler la croissance \u00e9conomique de l&rsquo;Alg\u00e9rie, en cr\u00e9ant des emplois dans la production, le stockage et le transport de l&rsquo;hydrog\u00e8ne. L\u2019id\u00e9e est d\u2019encourager le pays \u00e0 devenir un centre de r\u00e9f\u00e9rence dans l\u2019industrie mondiale de l&rsquo;hydrog\u00e8ne, avec l&rsquo;ambition d\u2019exporter cette \u00e9nergie propre \u00e0 des march\u00e9s internationaux.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 12 f\u00e9vrier 2025, l&rsquo;Alg\u00e9rie a renforc\u00e9 sa coop\u00e9ration avec l&rsquo;entreprise espagnole Coolergy pour d\u00e9velopper l&rsquo;hydrog\u00e8ne liquide. Ce partenariat vise \u00e0 produire et exporter de l&rsquo;hydrog\u00e8ne vert et bleu, avec un accent particulier sur la liqu\u00e9faction et le stockage. Il pourrait aussi stimuler la croissance \u00e9conomique et l&rsquo;exportation.<\/p>\n","protected":false},"author":5,"featured_media":100269,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-100268","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energie","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/100268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/comments?post=100268"}],"version-history":[{"count":0,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/posts\/100268\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media\/100269"}],"wp:attachment":[{"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/media?parent=100268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/categories?post=100268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/econostrum.info\/algerie\/wp-json\/wp\/v2\/tags?post=100268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}